{"id":40926,"date":"2024-07-16T10:34:24","date_gmt":"2024-07-16T10:34:24","guid":{"rendered":"https:\/\/martinopietropoli.com\/?p=40926"},"modified":"2024-07-18T10:38:30","modified_gmt":"2024-07-18T10:38:30","slug":"specchio-2","status":"publish","type":"post","link":"https:\/\/martinopietropoli.com\/en\/specchio-2","title":{"rendered":"Specchio"},"content":{"rendered":"<p><em>\u201cCon una delle mie studentesse di Harvard, Loralyn Thompson, decidemmo di fare un esperimento: distribuimmo ai pazienti un foglio che riportava un centinaio circa di descrittori di comportamenti e chiedemmo loro di cerchiare quelli che avrebbero voluto cambiare ma non ci riuscivano. Sull\u2019altro lato del foglio, in un ordine diverso, c\u2019erano le versioni positive di ciascuno di quei comportamenti. I pazienti dovevano cerchiare ci\u00f2 che apprezzavano di se stessi. Cos\u00ec, da un lato c\u2019erano parole come: incoerente, impulsivo, ingenuo, rigido e malinconico, e dall\u2019altro: flessibile, spontaneo, fiducioso, stabile e serio. Come vi sarete gi\u00e0 immaginati, per lo pi\u00f9 gli aspetti che i nostri pazienti tentavano di cambiare senza riuscirvi, erano gli stessi che \u2013 se messi sotto una luce positiva \u2013 apprezzavano di se stessi.\u201d<\/em><\/p>\n\n\n\n<p>Ellen J. Langer descrive cos\u00ec in \u201cIl corpo consapevole\u201d un esperimento che aveva lo scopo di dimostrare &#8211; o almeno cos\u00ec l\u2019ho letto io e lo conservo nella memoria &#8211; la dualit\u00e0 delle persone e quanto spesso, per non dire sempre, noi stessi non riusciamo a vederci altro che monodimensionali. Manchiamo insomma di cogliere la nostra profondit\u00e0.<\/p>\n\n\n\n<p>Se ci dovessimo descrivere, a ben pensarci, finiremmo per fornire di noi stessi una definizione che in parte \u00e8 mutuata da come gli altri ci descrivono, cio\u00e8 dall\u2019immagine che proiettiamo e che vediamo riflessa di noi stessi.<\/p>\n\n\n\n<p>A prescindere dal fatto che &#8211; per citare per l\u2019ennesima volta David Foster Wallace &#8211; di noi agli altri non gliene frega molto, \u00e8 interessante notare un sottotesto poco espresso di questo assunto: non siamo interessati a ci\u00f2 che gli altri pensano di noi ma al loro giudizio. Non cerchiamo insomma negli altri una dimensione riflessa che possa fornirci indizi sulla nostra vera natura ma solo il giudizio che la societ\u00e0 ha su di noi.<\/p>\n\n\n\n<p>Pensiero e giudizio sono due cose molto diverse, ma \u00e8 comodo o pratico confonderle.<\/p>\n\n\n\n<p>Per ritornare all\u2019esperimento iniziale: ci\u00f2 che le persone riconoscevano in se stesse come difetto era anche definito come una qualit\u00e0. L\u2019unica differenza era il nome con cui queste caratteristiche erano chiamate. Chi si riconosce come poco istintivo e troppo riflessivo pu\u00f2 altrimenti definirsi come un ottimo osservatore, chi \u00e8 poco espansivo pu\u00f2 altrimenti considerarsi rispettoso dei confini altrui.<\/p>\n\n\n\n<p>Abbiamo diversi lati o forse \u00e8 meglio dire pi\u00f9 opposti: i difetti sono quelli immediatamente visibili nel riflesso sociale (cio\u00e8 in come gli altri ci vedono o pensiamo che ci vedano) mentre i pregi emergono solo dopo una lettura pi\u00f9 articolata, che giunge a sostenere che:<\/p>\n\n\n\n<ol class=\"wp-block-list\"><li>L\u2019opposto di un difetto pu\u00f2 essere un pregio<\/li><li>Conteniamo opposti<\/li><li>Il negativo \u00e8 un\u2019immagine riflessa, e per di pi\u00f9 filtrata attraverso il giudizio personale (che non \u00e8 ci\u00f2 che gli altri pensano ma ci\u00f2 che pensiamo che gli altri pensino, cio\u00e8 una specie di inception del giudizio, per di pi\u00f9 presupposto).<\/li><\/ol>\n\n\n\n<p>Riporto questi ragionamenti perch\u00e9 ci ho riflettuto ultimamente e non nego che l\u2019idea che i difetti siano pregi \u00e8 un ottimo esercizio per l\u2019autostima. L\u2019unico difetto \u00e8 che non funziona in tutti i casi e pu\u00f2 non incontrare l\u2019accordo e la comprensione altrui ma per il bene della scienza e di queste parole qui dette immaginiamo che funzioni alla perfezione.<\/p>\n\n\n\n<p>La parte pi\u00f9 interessante mi pare essere quella del giudizio sociale. Ricostruendo il ragionamento:<\/p>\n\n\n\n<ol class=\"wp-block-list\"><li>L\u2019immagine che abbiamo di noi \u00e8 un\u2019immagine ma non siamo noi<\/li><li>L\u2019immagine rappresenta noi, riflessi nel contesto sociale<\/li><li>L\u2019essenza individuale \u00e8 libera dalla componente sociale.<\/li><\/ol>\n\n\n\n<p>Ora: come \u00e8 possibile annullare il contributo della dimensione sociale alla percezione di noi stessi?<\/p>\n\n\n\n<p>Una delle forme di conoscenza innate \u00e8 quella per affinit\u00e0, che \u00e8 contraria a quella per differenza. Ci si identifica e riconosce in altri caratteri (persone) simili o ci si definisce in quanto diversi da altri.<\/p>\n\n\n\n<p>C\u2019\u00e8 per\u00f2 un\u2019altra forma di conoscenza pi\u00f9 emotiva e profonda che supera (o non attinge) alla dimensione razionale e al confronto. Esistono persone o condizioni che mettono in vibrazione il&nbsp;<em>corpo psicologico<\/em>&nbsp;(con questa espressione intendo un insieme pi\u00f9 ampio della sola mente, come se la mente non fosse solo contenuta nella scatola cranica ma avesse un\u2019intelligenza che si espande a tutti i sensi del corpo). Non \u00e8 detto che sia scontato incontrarle n\u00e9 tantomeno inevitabile: si potrebbe vivere una vita intera pensando che l\u2019unica dimensione sia quella sociale e che l\u2019essenza individuale si risolva nel riflesso in questo unico ambito.<\/p>\n\n\n\n<p>Quando per\u00f2 capita di intercettare questi altri corpi psicologici si entra in risonanza e si percepisce una natura intima pi\u00f9 complessa e profonda cui la superficialit\u00e0 del contesto sociale non pu\u00f2 attingere.<\/p>\n\n\n\n<p>Non \u00e8 una risonanza razionale o almeno non \u00e8 percepita come tale. Non si esprime in un lampo di chiarezza inequivocabile. Direi piuttosto che emana bagliori di colori quasi violenti e impossibili da ignorare. Cose non usuali.<\/p>\n\n\n\n<p>Anche se il contatto di queste orbite esistenziali potrebbe far pensare che si tratti comunque di un\u2019esperienza sociale, non \u00e8 esattamente cos\u00ec: pu\u00f2 accadere anche con uno spazio o una musica. Sono esperienze che provocano reazioni e che manifestano una natura dell\u2019individuo che la sintesi della societ\u00e0 non pu\u00f2 cogliere. \u00c8 una condizione in cui non valgono le regole della convivenza e dell\u2019opportunit\u00e0, e precede la razionalit\u00e0. \u00c8 animale e innata, appunto.<\/p>\n\n\n\n<p>Innesca un riverbero, una vibrazione.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p>Giorni fa mi sono ritrovato davanti a un quadro specchiante di Pistoletto. La figura ritratta era quella di un uomo di spalle. Queste opere concettuali &#8211; come la buona arte contemporanea sa fare &#8211; richiedono la presenza dell\u2019osservatore giacch\u00e9 lo portano dentro l\u2019opera stessa. Osservando questo specchio ci si ritrova riflessi e quindi si fa parte dell\u2019opera d\u2019arte. Si potrebbe dire che essa non esisterebbe o non esaurirebbe la sua funzione se non la attivasse l\u2019osservatore. Un aspetto interessante di quest\u2019opera \u00e8 che l\u2019uomo di spalle non \u00e8 riflesso: di lui non si vede il volto ma solo ci\u00f2 che lo specchio non fa mai vedere: la schiena. Lo specchio pu\u00f2 riflettere solo un lato e quindi una sola dimensione. Lo specchio non ha profondit\u00e0. L\u2019unica figura riflessa \u00e8 quella dell\u2019osservatore.<\/p>\n\n\n\n<p>Mi sono guardato riflesso in quello specchio e ho capito che quello che la persona di spalle stava osservando ero io, mentre io potevo osservare solo la sua schiena. Si tratta insomma di un curioso specchio che non riflette una figura e ne riflette solo un\u2019altra (quella dell\u2019osservatore, che inoltre vede il lato oscuro della luna, cio\u00e8 quello che lo specchio non pu\u00f2 vedere).<\/p>\n\n\n\n<p>L\u2019arte contemporanea riesce a tradurre in un\u2019immagine quanto ho detto in molte parole sin qui: che siamo corpi (psicologici) con pi\u00f9 dimensioni e con almeno due facce opposte. Che non siamo definiti da un\u2019unica dimensione. Che, infine, pi\u00f9 che il giudizio o il pensiero della societ\u00e0, dovremmo cercare ci\u00f2 che fa riverberare questo corpo impalpabile che conteniamo. E che difficilmente possiamo conoscere. Un modo \u00e8 pensare di essere composti da opposti. Un altro \u00e8 vibrare, cercando di vedere la nostra stessa schiena.<\/p>","protected":false},"excerpt":{"rendered":"<p>Il riflesso di una persona non \u00e8 la persona stessa<\/p>","protected":false},"author":1,"featured_media":40927,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[91,114,415,429],"tags":[573,525],"class_list":["post-40926","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura","category-featured","category-pensiero-lungo","category-umanesimo","tag-personalita","tag-psicologia"],"acf":[],"_links":{"self":[{"href":"https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/posts\/40926","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/comments?post=40926"}],"version-history":[{"count":0,"href":"https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/posts\/40926\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/media\/40927"}],"wp:attachment":[{"href":"https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/media?parent=40926"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/categories?post=40926"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/tags?post=40926"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}