{"id":40813,"date":"2024-03-24T20:55:00","date_gmt":"2024-03-24T20:55:00","guid":{"rendered":"https:\/\/martinopietropoli.com\/?p=40813"},"modified":"2024-03-25T21:09:28","modified_gmt":"2024-03-25T21:09:28","slug":"squarcio","status":"publish","type":"post","link":"https:\/\/martinopietropoli.com\/en\/squarcio","title":{"rendered":"Squarcio"},"content":{"rendered":"<p>Un giorno ho capito che il tempo a cui penso \u00e8 quello che resta, cio\u00e8 il futuro. O anche: ho pensato che il futuro non \u00e8 solo una proiezione o il dominio delle congetture, delle speranze e delle eventuali ansie ma ha anche una dimensione definita, cio\u00e8 ha una natura. \u201cDefinita\u201d non significa n\u00e9 precisa n\u00e9 determinata: significa che \u00e8 fatto di una pasta particolare, ma ovviamente non se ne possono conoscere i confini. Il futuro \u00e8 ci\u00f2 che \u00e8 di fronte, ci\u00f2 che deve ancora accadere, il regno delle possibilit\u00e0.<\/p>\n\n\n\n<p>Il passato \u00e8 una memoria ad accesso casuale: dalla memoria si estraggono unit\u00e0 particolari che rappresentano ricordi. Non si contiene tutto il passato ma solo alcune sue registrazioni: una giornata di 5 anni fa, una telefonata di 12 anni fa, un tramonto visto la scorsa primavera. Il futuro \u00e8 una massa indistinta e compatta e densa (non ha ancora forma) mentre il passato \u00e8 un archivio. Certe unit\u00e0 memorizzate non verranno mai pi\u00f9 richiamate alla mente e osservate, certe altre invece s\u00ec.&nbsp;<\/p>\n\n\n\n<p>Alcune di queste unit\u00e0 hanno una particolare intensit\u00e0: hanno colori pi\u00f9 definiti, odori pi\u00f9 chiari, suoni pi\u00f9 saturi. Perch\u00e9 ne ricordo alcune? Il motivo \u00e8 semplice: perch\u00e9 non sono solo memorie ma sono punti nodali della mia esistenza. Quando li ho vissuti per\u00f2 non lo sapevo. Io non saprei definire quegli avvenimenti che poi diventano luoghi della memoria se non come portali in cui le dimensioni del passato e del futuro si toccano, nel presente.\u00a0<\/p>\n\n\n\n<p>Per esempio ricordo un giorno in cui fermai la macchina senza motivo e guardai il fiume scorrere e sull\u2019argine opposto degli alberi. Era primavera, il cielo era sereno. Mi resi conto di essere totalmente indifferente alla Natura. Niente in particolare lo suggeriva ma tutto lo diceva. Ne fui sollevato e rasserenato: non avere alcuna importanza nell\u2019ordine cosmico era liberatorio invece che deprimente. Essere una parte del tutto e contemporaneamente il centro di niente pone in una nuova prospettiva e sgrava di certe responsabilit\u00e0.<\/p>\n\n\n\n<p>Un\u2019altra volta guardavo una piscina. Fu quando pensai che avrei dovuto nuotare. Dopo pochi giorni iniziai a farlo davvero.&nbsp;<\/p>\n\n\n\n<p>Non ho mai pianificato molto nella mia vita, non ho mai voluto intralciare i piani che il destino aveva per me, ammesso poi che li avesse. Quindi il fatto che i lembi del passato e del futuro possano toccarsi in un punto del presente non \u00e8 solo un fenomeno metafisico esperibile del regno fisico: \u00e8 anche una sorta di rappresentazione del destino.&nbsp;<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-center\" style=\"font-size:24px\"><em>Il futuro che si manifesta \u00e8 la forma con cui il destino esplode in bagliori improvvisi e imprevedibili.<\/em><\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Il problema semmai \u00e8 vederli, \u00e8 accorgersene. Se per\u00f2 penso a questi due avvenimenti mi rendo conto che sono accaduti in condizioni identiche: non stavo facendo niente se non guardare. Non stavo giudicando, non stavo pensando ad altro, non volevo essere in un altro luogo. Ero in un momento nel tempo in cui dovevo &#8211; evidentemente &#8211; trovarmi. Il futuro quindi \u00e8 un treno che arriva al binario dove \u00e8 previsto che tu ti trovi. In una stazione invisibile, a un orario sconosciuto. L\u2019unica condizione \u00e8 farsi trovare sul luogo al momento giusto.<\/p>\n\n\n\n<p>Parlo di futuro perch\u00e9 questi due ricordi sono particolarmente significativi avendo rappresentato un punto nodale della mia vita. Dopo qualcosa \u00e8 cambiato e i semi del cambiamento erano contenuti in quelle immagini rivelatesi in pochi istanti. Non ha molta importanza dire in cosa e perch\u00e9 sono stati punti di svolta: in fondo lo sono stati per me e l\u2019interesse si ferma l\u00ec. Tanti altri attimi hanno corretto la mia traiettoria esistenziale, solo che non me ne sono mai reso conto. Questi invece li ho visti e, a ben vedere, non \u00e8 un vantaggio da poco. Se dovessi scriverne una sceneggiatura della mia vita non potrei ometterli, sarebbero dei cardini della storia.<\/p>\n\n\n\n<p>Altri li chiamerebbero epifanie: momenti in cui qualcosa si rivela. La condizione perch\u00e9 ci\u00f2 avvenga \u00e8 essere vigili, attenti, dediti solo all\u2019osservazione, come io su quell\u2019argine o come&nbsp;<\/p>\n\n\n\n<p><a href=\"https:\/\/open.substack.com\/users\/2764316-silvio-castelletti?utm_source=mentions\" target=\"_blank\" rel=\"noreferrer noopener\">Silvio Castelletti<\/a>&nbsp;racconta di&nbsp;<a href=\"https:\/\/substack.com\/inbox\/post\/142806021\">Murakami<\/a>, di quando cio\u00e8, assistendo a una partita di baseball, il suono che la mazza provoc\u00f2 all\u2019impatto della palla gli fece decidere che avrebbe scritto un romanzo.&nbsp;<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-center\" style=\"font-size:24px\">\u201c<em>In that instant, for no reason and based on no ground whatsoever, it suddenly struck me:<\/em>\u00a0<em>I think I can write a novel<\/em>.\u201d<\/p>\n\n\n\n<div style=\"height:49px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Disse \u201cPenso di poter scrivere un romanzo\u201d, e non \u201cpenso che scriver\u00f2 un romanzo\u201d. C\u2019\u00e8 una differenza sostanziale (il linguaggio \u00e8 uno strumento preciso): la formulazione che adotta Murakami contiene la possibilit\u00e0 e non la certezza, quindi contiene il futuro. Del resto, che certezza avrebbe mai potuto avere? A quel punto della sua vita non era ancora uno scrittore e niente del suo vissuto avrebbe potuto decretare quello svolgimento della sua trama esistenziale. Eppure a una partita di baseball Murakami cap\u00ec che sarebbe diventato scrittore. O almeno che avrebbe potuto esserlo. I lembi di passato e futuro si toccarono, il portale si apr\u00ec e il destino si manifest\u00f2.<\/p>\n\n\n\n<p>Non si giunge in questi luoghi e in determinati momenti per caso. Non che vi sia bisogno di immaginare che sia una mano divina a rivelare qualcosa: pi\u00f9 umanamente, la vita ti ci porta. Esattamente come ora, per me che scrivo o per te, lettore che leggi:&nbsp;<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-center\" style=\"font-size:24px\"><em>Ora, in questo preciso istante, entrambi siamo esattamente dove la vita ci ha condotti. La somma degli attimi che compongono il passato ci ha condotti qui. Il presente \u00e8 il risultato di un\u2019equazione.<\/em><\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Infine: questi attimi hanno un\u2019altra particolarit\u00e0, cui prima accennavo. Non sono riconoscibili se non a posteriori. Pu\u00f2 darsi che, nell\u2019istante in cui si manifestano, la mente li percepisca come diversamente significativi ma la loro natura cardinale (nel senso che qualcosa, in quel punto temporale, inizia a ruotare e cambiare direzione) \u00e8 percepibile appena. Sono attimi che alterano il reale, sono perturbazioni nel campo, sono correnti e onde provenienti da altrove.<\/p>\n\n\n\n<p>Sono gli attimi che diventano memorie che rifulgono solo dopo un po\u2019 di tempo. Quando qualcosa \u00e8 cambiato ci si guarda indietro, ci si accorge che la direzione \u00e8 diversa e, se lo sguardo della mente penetra abbastanza nella memoria, si vede con chiarezza che la strada piegava proprio in quel punto.<\/p>\n\n\n\n<p>Il fenomeno richiede condizioni precise per accadere: serve lo spazio interiore, serve la mente sgombra, servono gli occhi per vedere: un albero dall\u2019altra parte del fiume, una piscina, la palla da baseball che colpisce una mazza.<\/p>\n\n\n\n<p>La condizione che accomuna queste esperienze \u00e8 che ci si accorge di qualcosa perch\u00e9 ci si fa vuoti (pronti ad accogliere) e si indugia nell\u2019osservazione. L\u2019essere nel presente richiede di non pensare n\u00e9 al passato n\u00e9 al futuro. Allora ci si pu\u00f2 riempire di ogni atomo del presente.&nbsp;<\/p>\n\n\n\n<p>Quel giorno sull\u2019argine mi accorsi di un altro particolare: il fiume scorreva nel senso opposto a quello che avevo sempre pensato. Per una vita intera avevo visto quel fiume senza mai vederlo davvero. Forse il futuro si lascia intravedere solo quando si \u00e8 predisposti a osservare avendo fatto il vuoto nella mente. Solo allora, finalmente, tutto ci pu\u00f2 attraversare e lasciare i sedimenti di ci\u00f2 che non \u00e8 ancora e che presto sar\u00e0.<\/p>","protected":false},"excerpt":{"rendered":"<p>Un portale in cui il passato e il futuro si toccano, descritto senza mai fare riferimento alla fisica quantistica<\/p>","protected":false},"author":1,"featured_media":40814,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[91,415,429],"tags":[],"class_list":["post-40813","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura","category-pensiero-lungo","category-umanesimo"],"acf":[],"_links":{"self":[{"href":"https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/posts\/40813","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/comments?post=40813"}],"version-history":[{"count":0,"href":"https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/posts\/40813\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/media\/40814"}],"wp:attachment":[{"href":"https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/media?parent=40813"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/categories?post=40813"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/tags?post=40813"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}