{"id":39619,"date":"2023-07-07T09:59:00","date_gmt":"2023-07-07T09:59:00","guid":{"rendered":"https:\/\/martinopietropoli.com\/?p=39619"},"modified":"2023-11-13T22:23:47","modified_gmt":"2023-11-13T22:23:47","slug":"rappresentazione","status":"publish","type":"post","link":"https:\/\/martinopietropoli.com\/en\/rappresentazione","title":{"rendered":"Rappresentazione\u00a0"},"content":{"rendered":"<p>30 anni fa andai a New York per la prima volta. Ricordo che quando scesi dall\u2019aereo mi meravigliai che nessuno mi avesse ancora sparato addosso. Ero sul suolo statunitense da pochi minuti eppure non era ancora successo quello che &#8211; per chi avesse visto almeno una serie televisiva americana in tutta la sua vita &#8211; era scontato: negli USA si sparano tutti. O almeno quella era l\u2019immagine che se ne aveva, basandosi sul cinema e le storie che da l\u00e0 arrivavano.<\/p>\n\n\n\n<p>Scoprii il mattino dopo che erano altre le cose che mi stupivano di quel luogo, e sarebbe stato difficile prevederle: ricordo in particolare la dimensione inusitata (eccessiva) dei cornetti e i secchi di caff\u00e8 con cui molti newyorkesi giravano per strada. Dico \u201csecchi\u201d anche se erano comuni bicchieri di carta, ma di dimensioni pantagrueliche.&nbsp;<\/p>\n\n\n\n<p>Non voglio comunque parlare delle mie impressioni sugli USA o su New York (due cose che i puristi ci tengono a distinguere, perch\u00e9 New York \u00e8 la meno americana delle citt\u00e0 ecc. ecc.) quanto piuttosto dell\u2019effetto che i racconti, i film, la musica di quel paese o di quella citt\u00e0 avevano costruito nella mia mente.\u00a0<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-center\" style=\"font-size:24px\"><em>Il racconto della realt\u00e0 non \u00e8 uguale alla realt\u00e0, cos\u00ec come la mappa non \u00e8 il territorio.<\/em><\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Si dice che la letteratura amplifichi ed estenda la vita perch\u00e9 permette di vivere vite altrui. Le parole, le immagini e, in genere, le storie, sono un modo mediato per dare un\u2019idea di qualcosa. Credendo che mi avrebbero sparato non appena sceso dall\u2019aereo, in fondo credevo ingenuamente che la rappresentazione di una citt\u00e0 fosse la citt\u00e0 stessa. Che la descrizione dei suoi abitanti coincidesse con gli abitanti stessi.<\/p>\n\n\n\n<p>Il racconto ha un\u2019esigenza di sintesi: uno scrittore non pu\u00f2 dire tutto, cos\u00ec come un regista si concentra su una storia o un fotografo sceglie l\u2019inquadratura operando l\u2019esclusione di tutto il resto (ci\u00f2 che non \u00e8 nel fotogramma \u00e8 altrettanto importante di ci\u00f2 che vi \u00e8, cio\u00e8 la sua assenza d\u00e0 sostanza a ci\u00f2 che \u00e8 visibile, perch\u00e9, se fosse altrettanto visibile, toglierebbe potenza a ci\u00f2 che si vuole significare, diluendo e stemperando il messaggio).<\/p>\n\n\n\n<p>Del resto\u00a0<em>rappresentare<\/em>\u00a0significa \u201crendere nuovamente presente\u201d, rievocando attraverso immagini o parole ci\u00f2 che non \u00e8 materialmente di fronte agli occhi dell\u2019osservatore. La rappresentazione contiene in s\u00e9 la sintesi della realt\u00e0, e, come tale, esclude o pone in secondo piano i dettagli. In altre parole, la realt\u00e0 \u00e8 tutto, la sua rappresentazione \u00e8 l\u2019esito di un\u2019operazione di sintesi e depurazione.<\/p>\n\n\n\n<p>In questi termini, la rappresentazione parrebbe una forma spuria di realt\u00e0, una sua specie di sottoprodotto. Del resto \u00e8 naturale pensare che il tutto abbia pi\u00f9 valore della parte, per di pi\u00f9 se questa \u00e8 selezionata, soggettiva, puntuale ed escludente. Si potrebbe altrimenti dire che la rappresentazione \u00e8 la realt\u00e0 filtrata dalla mente, ridotta ai suoi elementi salienti secondo il vaglio della mente. La realt\u00e0 \u00e8 un oggetto ontologico, la rappresentazione \u00e8 un oggetto mentale. La realt\u00e0 esiste indipendentemente dalla mente, mentre la rappresentazione ha bisogno della mente per esistere.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Una domanda senza risposta<\/h4>\n\n\n\n<p>Queste considerazioni mi sono tornate alla mente visitando la straordinaria mostra&nbsp;<em>Eveningside<\/em>&nbsp;di<\/p>\n\n\n\n<p><a href=\"https:\/\/open.substack.com\/users\/22893454-gregory-crewdson?utm_source=mentions\" target=\"_blank\" rel=\"noreferrer noopener\">Gregory Crewdson<\/a>ad Arles, che tra l\u2019altro credo sia<a href=\"https:\/\/gallerieditalia.com\/it\/torino\/mostre-e-iniziative\/mostre\/2022\/10\/12\/gregory-crewdson-eveningside\/\">&nbsp;la stessa che era a Torino<\/a>.<\/p>\n\n\n\n<p>Crewdson \u00e8 famoso per le sue fotografie stampate in grande formato e ricchissime di dettagli. Per far meglio capire di quale universo visivo si parla, si potrebbe descriverlo come l\u2019Hopper della fotografia, anche se i fotografi si innervosiscono quando si dice delle loro foto che sembrano quadri, e i pittori viceversa. Per\u00f2 \u00e8 anche il modo pi\u00f9 immediato per descrivere l\u2019immaginario a cui Crewdson esplicitamente si riferisce: quello di un\u2019America di provincia, decadente, di piccoli centri urbani che si sviluppano lungo strade polverose e hanno la forma di case di legno abitate da solitudini disperate.<\/p>\n\n\n\n<p>Ogni sua foto \u00e8 una gioia per gli occhi per l\u2019accuratezza maniacale della costruzione, e molto spesso si tratta di veri e propri set preparati come se vi si dovesse girare un film. Solo che lui scatta solo una fotografia. E dentro ci sono attori che interpretano persone normali colte in un istante meditativo o disperato della loro vita.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/www.instagram.com\/p\/CtRwvoAOU7Y\/\" target=\"_blank\" rel=\"noreferrer noopener\"><img decoding=\"async\" src=\"https:\/\/substackcdn.com\/image\/fetch\/w_2400,c_limit,f_auto,q_auto:good,fl_progressive:steep\/https%3A%2F%2Fsubstack-post-media.s3.amazonaws.com%2Fpublic%2Fimages%2F1c6db36d-087e-4571-8e90-c1fe8df9ce80_1190x767.jpeg\" alt=\"\"\/><\/a><figcaption>Gregory Crewdson,&nbsp;<a href=\"https:\/\/www.instagram.com\/p\/CtRwvoAOU7Y\/\">Untitled, 2003<\/a>&nbsp;(Unreleased Beneath the Roses&nbsp;<a href=\"https:\/\/www.instagram.com\/explore\/tags\/4\/\">#4<\/a>,)<\/figcaption><\/figure>\n\n\n\n<p>Quello che voglio dire \u00e8 che la fotografia di Crewdson rappresenta evidentemente una sua idea della condizione umana e non solo: rappresenta anche una precisa incarnazione dell\u2019immagine dell\u2019entroterra statunitense e di una parte non marginale di quel paesaggio geografico, urbano e umano. Racconta, in altre parole, delle storie americane che usano parole universali: quelle delle immagini.&nbsp;<\/p>\n\n\n\n<p>Allora mi sono chiesto se, al di l\u00e0 dell\u2019evidente citazione hopperiana, le sue foto rappresentino un\u2019idea di USA o se creino in chi le osserva l\u2019idea che quelli ritratti siano gli USA. In altre parole:\u00a0<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-center\" style=\"font-size:24px\"><em>Cosa \u00e8 reale? La realt\u00e0 o la sua rappresentazione?\u00a0<\/em><\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Non \u00e8 un quesito marginale perch\u00e9, come dicevo prima, la rappresentazione pu\u00f2 essere anche creazione, ossia &#8211; secondo certe modalit\u00e0 &#8211; la rappresentazione del reale potrebbe anche non riferirsi a un reale esistente ma crearlo, dal nulla.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/www.instagram.com\/p\/CqMFuJGuCbW\/\" target=\"_blank\" rel=\"noreferrer noopener\"><img decoding=\"async\" src=\"https:\/\/substackcdn.com\/image\/fetch\/w_2400,c_limit,f_auto,q_auto:good,fl_progressive:steep\/https%3A%2F%2Fsubstack-post-media.s3.amazonaws.com%2Fpublic%2Fimages%2Fcbbcceed-adb4-4123-a000-329118328ef4_1688x1256.png\" alt=\"\"\/><\/a><figcaption>The Lounge, 2021-2022<\/figcaption><\/figure>\n\n\n\n<p>\u00c8 probabile che l\u2019idea di USA di Crewdson sia plausibile: in fondo la conosciamo ed esiste materialmente, eppure la rappresentazione che lui ne d\u00e0 aggiunge altri livelli di lettura. Diciamo che la rende metafisica perch\u00e9 s\u00ec, le sue foto hanno forti elementi metafisici: si riferiscono a una realt\u00e0 fisica e reale ma le sovrappongono un velo che aggiunge significati. Sono, insomma,&nbsp;<em>metafotografie<\/em>.<\/p>\n\n\n\n<p>La domanda non ha quindi una risposta precisa e dirimente o entrambe le tesi sono verificate:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Crewdson rappresenta l\u2019America reale<\/li><li>Crewdson crea un\u2019idea d\u2019America e la rende reale attraverso la fotografia.&nbsp;<\/li><\/ul>\n\n\n\n<p>In definitiva usa un linguaggio visivo per raccontare storie di solitudine, morte, disperazione e abbandono. E raccontando storie, crea nuovi mondi, in cui i luoghi e le persone sono private della loro individualit\u00e0 e diventano universali. Quello che si vede rappresentato \u00e8, quindi, un simulacro di qualcosa di pi\u00f9 grande che, come tale, contiene anche le solitudini dell\u2019individualit\u00e0.<\/p>\n\n\n\n<p>In altri termini, il paradosso \u00e8 che la rappresentazione &#8211; attraverso il racconto &#8211; pu\u00f2 creare la realt\u00e0, generando un cortocircuito fra due cose distinte, sconvolgendo le gerarchie: la rappresentazione insomma non ha sempre bisogno di derivare da una realt\u00e0 per esistere ma pu\u00f2 anzi creare una realt\u00e0, plausibile o meno.<\/p>\n\n\n\n<p>Perch\u00e9 l\u2019umanit\u00e0 rappresenta la realt\u00e0 invece di guardarla e basta? La risposta pi\u00f9 semplice \u00e8 \u201cperch\u00e9 pu\u00f2 farlo\u201d ma \u00e8 chiaro che il motivo \u00e8 un po\u2019 pi\u00f9 profondo.<\/p>\n\n\n\n<p>La rappresentazione richiede un processo di elaborazione e ne restituisce una lettura. \u00c8 l\u2019esito di un giudizio, di una scelta: racconta cose, non ne racconta altre, seleziona, filtra, include ed esclude.&nbsp;<\/p>\n\n\n\n<p>Perch\u00e9 per\u00f2 non raccontare tutto e basta? Perch\u00e9 il&nbsp;<em>tutto&nbsp;<\/em>\u00e8 incomprensibile e non rappresentabile e, se lo fosse, sarebbe una copia esatta del reale. Non avrebbe senso, perch\u00e9 non aggiungerebbe alcun livello alla comprensione del reale, ammesso che esista una qualche spiegazione.&nbsp;<\/p>\n\n\n\n<p>Una copia di un originale non aggiunge significato all\u2019originale e non fa che duplicarne l\u2019essenza. Una copia di un originale &#8211; una copia della realt\u00e0, nel caso specifico &#8211; aggiunge solo un caos uguale al caos esistente.&nbsp;<\/p>\n\n\n\n<p>Ecco perch\u00e9 esiste la rappresentazione: per ordinare il reale e dargli una forma che non solo \u00e8 pi\u00f9 sintetica e allusiva, ma \u00e8 anche una copia diversa dell\u2019originale, cio\u00e8 un nuovo originale.<\/p>\n\n\n\n<p>Per tornare alla domanda iniziale: la rappresentazione non \u00e8 (solo) una sintesi della realt\u00e0 ma \u00e8 anche e soprattutto una nuova realt\u00e0. Insomma: la realt\u00e0 \u00e8 un&nbsp;<em>dato<\/em>, la sua rappresentazione \u00e8 un&nbsp;<em>generato<\/em>.<\/p>\n\n\n\n<p>Crewdson e l\u2019arte in genere allora cosa fanno? Creano una narrazione alternativa o rappresentano con precisione una realt\u00e0 esistente? Forse entrambe le cose: il suo punto di partenza \u00e8 sempre la realt\u00e0 ma l\u2019esito \u00e8 altrove e non \u00e8 pi\u00f9 solo radicato nella realt\u00e0. La rappresenta ma non \u00e8 la stessa cosa.&nbsp;<\/p>\n\n\n\n<p>Visitando i luoghi di Crewdson non si trovano quelle stesse persone ma altre molto simili. Non c\u2019\u00e8 quindi sovrapposizione di realt\u00e0 e suo racconto: sono due cose distinte, per quanto il racconto sia costruito con immagini che alludono alla realt\u00e0.<\/p>\n\n\n\n<p>Da una parte c\u2019\u00e8 insomma la realt\u00e0 ontologica (del reale) e dall\u2019altra quella logica (del racconto). Oppure: da una parte c\u2019\u00e8 il tutto e dall\u2019altra la sintesi, opera della logica. O infine: da una parte il tutto, e dall\u2019altra il logos, cio\u00e8 la parola. Non a caso in principio c\u2019era il verbo, come dice il Vangelo di Giovanni.&nbsp;<\/p>\n\n\n\n<p>E alla citazione biblica mi fermo.<\/p>","protected":false},"excerpt":{"rendered":"<p>Il racconto della realt\u00e0 crea la realt\u00e0 o la descrive?<\/p>","protected":false},"author":1,"featured_media":39620,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[94,415,429],"tags":[76,526,77,527,528],"class_list":["post-39619","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fotografia","category-pensiero-lungo","category-umanesimo","tag-fotografia","tag-gregory-crewdson","tag-photography","tag-rappresentazione","tag-storie"],"acf":[],"_links":{"self":[{"href":"https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/posts\/39619","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/comments?post=39619"}],"version-history":[{"count":0,"href":"https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/posts\/39619\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/media\/39620"}],"wp:attachment":[{"href":"https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/media?parent=39619"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/categories?post=39619"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/tags?post=39619"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}