{"id":38371,"date":"2022-08-29T14:17:46","date_gmt":"2022-08-29T14:17:46","guid":{"rendered":"https:\/\/martinopietropoli.com\/?p=38371"},"modified":"2022-10-23T23:16:07","modified_gmt":"2022-10-23T23:16:07","slug":"quel-che-resta","status":"publish","type":"post","link":"https:\/\/martinopietropoli.com\/en\/quel-che-resta","title":{"rendered":"Quel che resta"},"content":{"rendered":"<p>Fra tutti i pensieri lunghi &#8211; assieme a quello sulla morte &#8211; quello sul senso della vita ha analogo momento e potenza. Qual \u00e8 il motivo e lo scopo della nostra vita?<br>Naturalmente non lo so. Il grande George Carlin ne dava una spiegazione intelligente e perfettamente autoreferenziale (o autoreferenziata):<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><em>Il senso della vita \u00e8 la vita stessa.<\/em><\/p><\/blockquote>\n\n\n\n<p>Potrebbe sembrare una spiegazione semplice, incompleta o anche perfidamente intellettuale ma contiene alcune o tutte le verit\u00e0. Una delle quali \u00e8 che il senso della vita non pu\u00f2 che essere contenuto dalla vita stessa. Pu\u00f2 quindi significare &#8211; in un atteggiamento squisitamente fatalista &#8211; che il disegno esistenziale esula dalla nostra volont\u00e0 e che questa si svolge comunque indipendentemente dalla direzione che le diamo. La vit\u00e0 \u00e8 quindi un\u2019identit\u00e0, si autodetermina, \u00e8 ci\u00f2 che deve comunque essere e ci\u00f2 che era previsto e destino fosse. La saggezza sta nell\u2019accettarla.<\/p>\n\n\n\n<p>Un altro possibile approccio definisce il senso della vita in ci\u00f2 che lasciamo. La nostra eredit\u00e0 &#8211; in particolare quella affettiva e intellettuale &#8211; \u00e8 infatti il peso della nostra vita, il suo senso. Se il senso \u00e8 l\u2019esito di una costruzione esistenziale, la forma che ha l\u2019edificio morale e intellettuale che ergiamo \u00e8 il senso stesso della vita. Il nostro scopo \u00e8 lasciare qualcosa e l\u2019ironia &#8211; o il genio &#8211; di questa lettura \u00e8 che costruiamo qualcosa di cui non possiamo godere quando il suo disegno e la sua essenza saranno evidenti, cio\u00e8 alla fine della nostra vita.<br>Se infatti il senso \u00e8 quel che rimane di noi &#8211; il ricordo, l\u2019affetto, il lascito intellettuale (per una volta lasciamo stare quello economico, se c\u2019\u00e8 poi), allora costruiamo ci\u00f2 che lasciamo e ci\u00f2 di cui non potremmo godere. Una beffa, ma solo da un punto di vista, e cio\u00e8 quello egoistico. Se si abbandona questa visione e si costruisce un\u2019esistenza per accumulare ci\u00f2 di cui non si godr\u00e0 ma di cui godranno gli altri, allora si supera l\u2019egoismo.<\/p>\n\n\n\n<p>Ci pensavo in queste ultime settimane assistendo al riverbero di due morti scollegate fra di loro: quella di Piero Angela e quella di un ex-compagno di universit\u00e0. Del primo ho scritto che \u201calla fine ci ha spiegato anche come si fa a morire\u201d e mi pare che riassuma il suo anelito didattico perfettamente, dato che dopo averci spiegato per decenni le cose di scienza e di natura, alla fine ci ha dato una lezione su come morire e cosa lasciare: un buon sapore in bocca, un bel ricordo, una mancanza profonda compensata dalla ricchezza intellettuale che ci aveva donato in vita.<br><\/p>\n\n\n\n<p>L\u2019altra vita &#8211; o meglio, l\u2019altra morte &#8211; che mi ha ricordato quella di Angela \u00e8 stata quella di un mio coetaneo. Non sapevo stesse male, non ne sapevo niente. Come ormai succede, specie con chi non si ha rapporti continuativi, l\u2019ho saputo casualmente da Facebook. Nel tentativo di capire cosa fosse successo e se avessi inteso bene, ho scorso le decine di messaggi commossi di amici e sono stato riempito da un sentimento di dolore ma soprattutto di gratitudine e gioia per cosa aveva significato vivere anche nella vita di questa persona, per cos\u00ec tante persone.<br>E allora mi sono detto che anche quello era il senso della vita, cio\u00e8 alla fine, ancora una volta, quel che si lascia, quel che resta e se \u00e8 un senso cos\u00ec potente di amore, una gioia commovente alla fine, allora un senso molto chiaro c\u2019\u00e8.<br><\/p>\n\n\n\n<p>Una delle cose che ho letto in un libro di cui ho gi\u00e0 parlato &#8211; e cio\u00e8 \u201cCome cambiare la tua mente\u201d di Michael Pollan &#8211; \u00e8 il modo in cui molto spesso chi ha esperienze con sostanze allucinogene parla del viaggio fatto. Non avendo parole sufficienti a descriverlo, molti dicono che alla fine la cosa gli \u00e8 apparsa chiara in tutta la sua potenza e ineluttabilit\u00e0: il senso ultimo \u00e8 l\u2019amore, l\u2019unica energia \u00e8 l\u2019amore, tutti partecipiamo di un\u2019unica sostanza che \u00e8 fatta d\u2019amore.<br>Quel che pu\u00f2 sembrare una spiegazione decisamente new age ha invece un senso pi\u00f9 profondo: in parte legato al fatto che quel genere di esperienze &#8211; per ammissione di molti che le hanno vissute &#8211; non pu\u00f2 essere reso con il nostro linguaggio, e allora la cosa che ne pu\u00f2 dare un\u2019idea \u00e8 l\u2019Amore come sentimento totalizzante; in altra parte legato a una dimensione che \u00e8 prelogica, precedente al linguaggio e, come tale, non esprimibile a parole. Una dimensione che pu\u00f2 essere quindi ascrivibile all\u2019Amore.<br><\/p>\n\n\n\n<p>Il senso della vita non \u00e8 quindi esprimibile n\u00e9 comunicabile (\u00e8 pre-logico, come \u00e8 anche giusto che sia) e ha una dimensione pi\u00f9 universale di quella umana, tanto da non essere contenibile nei suoi egoismi e nelle sue piccolezze.<br>Il senso della vita di Angela o di Alessio \u00e8 quel che han lasciato: il profumo di un ricordo, un oggetto delicato che ci han lasciato in mano senza dirci cosa fosse, un\u2019esplosione di amore nel sentire e nel leggere come sono stati salutati. E il paradosso finale \u00e8 che non sapranno mai cosa \u00e8 restato di loro. Possono averlo intuito, perch\u00e9 hanno vissuto sapendo che quello importava lasciare, che cos\u00ec era importante vivere. Con amore, alla fine.<\/p>","protected":false},"excerpt":{"rendered":"<p>Il senso della vita<\/p>","protected":false},"author":1,"featured_media":38372,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[91,415],"tags":[162,409,78],"class_list":["post-38371","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura","category-pensiero-lungo","tag-morte","tag-senso-della-vita","tag-vita"],"acf":[],"_links":{"self":[{"href":"https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/posts\/38371","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/comments?post=38371"}],"version-history":[{"count":0,"href":"https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/posts\/38371\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/media\/38372"}],"wp:attachment":[{"href":"https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/media?parent=38371"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/categories?post=38371"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/tags?post=38371"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}