{"id":38210,"date":"2015-12-14T16:07:00","date_gmt":"2015-12-14T16:07:00","guid":{"rendered":"https:\/\/martinopietropoli.com\/?p=38210"},"modified":"2022-08-16T16:14:33","modified_gmt":"2022-08-16T16:14:33","slug":"larte","status":"publish","type":"post","link":"https:\/\/martinopietropoli.com\/en\/larte","title":{"rendered":"L&#8217;arte"},"content":{"rendered":"<p id=\"6e61\">Quale \u00e8 stata la prima opera d\u2019arte della storia dell\u2019uomo? Le pitture rupestri forse? Chi le fece non intendeva creare un\u2019opera d\u2019arte, anche perch\u00e9 l\u2019arte ancora non esisteva.<\/p>\n\n\n\n<p id=\"37ff\">Ci deve essere stato per\u00f2 un momento zero della creativit\u00e0 umana: il momento prima del quale l\u2019uomo non aveva mai creato niente di inutile, come solo l\u2019arte sa essere. Aveva creato utensili, aveva creato il fuoco (o scoperto, magari) e aveva imparato che il terreno poteva dare frutti. Forse il poter pensare ad altro che non fosse sopravvivere al giorno stesso, perch\u00e9 gi\u00e0 aveva riserve di cibo, gli permise di attivare il proprio cervello in una nuova dimensione: quella del futuro. Pens\u00f2 ad altro che alla sopravvivenza e quindi cre\u00f2 qualcosa di inutile: almeno non vitale, non necessario. Cre\u00f2 l\u2019arte.<\/p>\n\n\n\n<p id=\"9492\">L\u2019arte non serve a niente eppure esprime un\u2019idea, molto pi\u00f9 di quanto non la esprima un cervo cotto su un braciere o una focaccia fatta con il grano del raccolto. Tutte cose nobili e necessarie, ma non artistiche.<\/p>\n\n\n\n<p style=\"font-size:24px\"><em>Quando l\u2019uomo pot\u00e8 indulgere nel pensiero del\u00a0non immediato\u00a0cre\u00f2\u00a0l\u2019arte.<\/em><\/p>\n\n\n\n<p id=\"00ce\">Si dice, giustamente credo, che l\u2019artista ha una visione. Allo stesso tempo non credo che l\u2019arte esprima l\u2019artista: in un certo senso forse lo fa, ma credo sia pi\u00f9 corretto dire che esprime un\u2019esigenza dell\u2019artista. E poich\u00e9 l\u2019arte non \u00e8 attuale e presente ma si esprime nel futuro, essa d\u00e0 forma a ci\u00f2 che ancora non esiste. \u00c8 una visione, appunto.<\/p>\n\n\n\n<p style=\"font-size:24px\"><em>L\u2019artista vede ci\u00f2 che ancora non esiste, e lo esprime con\u00a0l\u2019arte.<\/em><\/p>\n\n\n\n<p id=\"e21c\">Basti pensare a una foto, ma di quelle che dicono qualcosa: una foto \u00e8 un\u2019espressione d\u2019arte quando mostra una realt\u00e0 che non era visibile a nessuno prima che il fotografo la fermasse. O la componesse. \u00c8 giusto parlare di composizione fotografica, perch\u00e9 quello fa il fotografo: arrangia elementi su una tavolozza quadrata o rettangolare. Li compone e li sistema entro una cornice e li fa comunicare fra loro e con l\u2019osservatore. Chi guarda una foto vede una realt\u00e0 che non aveva mai visto, che non era ancora presente e a cui il fotografo ha dato vita. L\u2019ha resa presente ma non trascinandola dal futuro o dall\u2019inespresso dove si trovava nel tempo odierno: rendendola visibile.<\/p>\n\n\n\n<p id=\"bddc\">Si&nbsp;dice anche che l\u2019arte non inventa pi\u00f9 niente, che tutto \u00e8 gi\u00e0 stato fatto o visto. Il che \u00e8 anche vero, ma non dice tutto. L\u2019arte \u00e8 una creazione e la creazione \u00e8 qualcosa che prima non c\u2019era. La componente del tempo \u00e8 fondamentale nell\u2019arte perch\u00e9 divide il momento che separa la non esistenza dall\u2019esistenza. Prima e dopo. Esserci o non esserci.<\/p>\n\n\n\n<p id=\"07ab\">L\u2019arte anticipa, sempre. Quando \u00e8 arte ovviamente. Mostrando il futuro realizza una visione e quando quella visione \u00e8 realt\u00e0 storica l\u2019arte si storicizza: ora \u00e8 collocata in un tempo umano e non pi\u00f9 intellettuale. Ora \u00e8 storia perch\u00e9 la storia l\u2019ha raggiunta e superata.<\/p>\n\n\n\n<p id=\"0945\">Per\u00f2 c\u2019\u00e8 un\u2019arte\u200a\u2014\u200ae capita molto raramente ma \u00e8 comune a tutte le opere d\u2019arte che superano i limiti del tempo e che parlano all\u2019uomo contemporaneo o non sono mai raggiunte dal tempo presente\u200a\u2014\u200ache non ha tempo. \u00c8 collocabile temporalmente ma conserva ancora un\u2019idea di futuro inespressa o non ancora realizzata.<\/p>\n\n\n\n<p id=\"5fe1\">Quindi \u00e8 davvero inutile l\u2019arte? Nella pratica lo \u00e8. Non si mangia l\u2019arte, non si mangia con l\u2019arte. Cos\u00ec come non si possiede il futuro perch\u00e9 non si pu\u00f2 possedere ci\u00f2 che non si ha e che non \u00e8 ancora neanche qualcosa. Ma l\u2019arte riesce a vederlo e a dargli una forma visibile e tangibile. \u00c8 un futuro possibile e che forse non lo sar\u00e0 mai, ma se non lo capiamo \u00e8 perch\u00e9 non abbiamo la capacit\u00e0 di farlo, perch\u00e9 non \u00e8 reale. Reale \u00e8 ci\u00f2 che \u00e8 visibile, ma l\u2019arte \u00e8 reale poich\u00e9 \u00e8 visibile, pur rimandando a una realt\u00e0 che ancora non \u00e8.<\/p>\n\n\n\n<p id=\"6b56\">Quanta arte ha anticipato i tempi, quanti sguardi su un futuro oscuro ai pi\u00f9 l\u2019arte ha saputo gettare. Romanzi considerati improbabili quando vennero pubblicati e poi superati dalla realt\u00e0 dopo poco. Quante immagini anticipate e poi raggiunte dalla storia. Eppure l\u2019arte le aveva raccontate, prima che accadessero.<\/p>\n\n\n\n<p id=\"fe88\">Nell&#8217;inutile lavorio dell\u2019uomo, nel suo proiettare immagini nel futuro e carpirle sta la differenza fra l\u2019uomo e il resto degli animali: che l\u2019uomo ha un senso del tempo e una visione. Gli animali non ce l\u2019hanno. L\u2019arte \u00e8 in fondo l\u2019espressione tangibile della differenza fra uomo e animale. Perch\u00e9 \u00e8 un parto della sua intelligenza che nella nascita dell\u2019opera porta con s\u00e9 non ci\u00f2 che \u00e8, ma ci\u00f2 che sar\u00e0.<\/p>","protected":false},"excerpt":{"rendered":"<p>Quella cosa inutile<\/p>","protected":false},"author":1,"featured_media":38211,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[90],"tags":[80,76],"class_list":["post-38210","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-art","tag-arte","tag-fotografia"],"acf":[],"_links":{"self":[{"href":"https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/posts\/38210","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/comments?post=38210"}],"version-history":[{"count":0,"href":"https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/posts\/38210\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/media\/38211"}],"wp:attachment":[{"href":"https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/media?parent=38210"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/categories?post=38210"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/tags?post=38210"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}