{"id":33676,"date":"2015-08-07T16:29:35","date_gmt":"2015-08-07T16:29:35","guid":{"rendered":"https:\/\/martinopietropoli.com\/?p=33676"},"modified":"2024-06-05T00:32:17","modified_gmt":"2024-06-05T00:32:17","slug":"la-critica-della-critica-della-ragion-pura","status":"publish","type":"post","link":"https:\/\/martinopietropoli.com\/en\/la-critica-della-critica-della-ragion-pura","title":{"rendered":"La critica della Critica della Ragion Pura"},"content":{"rendered":"<p id=\"6809\">Dalla copertina dell\u2019edizione Bompiani del celebre libro di Kant, un marziano che giungesse sulla terra nottetempo noterebbe che \u201cImmanuel Kant\u201d, almeno gerarchicamente parlando, ha un\u2019importanza fondamentale, giacch\u00e9 \u00e8 scritto pi\u00f9 in grande del resto. Se sapesse poi cos\u2019\u00e8 un libro ne dedurrebbe che quello \u00e8 il titolo, e che l\u2019autore \u00e8 tale \u201cCritica della Ragion Pura\u201d. Dato il doppio cognome, penserebbe il nostro amico verde, il signor Critica proviene dalla casata dei Ragion Pura.<\/p>\n<p id=\"2e66\">Lo stesso signor Critica, argomenterebbe, \u00e8 rappresentato nell\u2019immagine, con sguardo concentrato e rivolto verso il basso, probabilmente nell\u2019atto di guardare il suo gatto che mangia crocchette, o contemplativo delle schiere di studenti che nei secoli successivi alla stesura del pregno libello non vi avrebbero capito alcunch\u00e9.<\/p>\n<p id=\"14e6\">Tale Costantino Esposito si deve essere occupato di qualcosa di non chiaro e poi c\u2019\u00e8 una traduzione da un idioma sconosciuto \u201ca fronte\u201d, qualsiasi cosa significhi.<\/p>\n<p id=\"d58e\">Sotto l\u2019immagine altre scritte di difficile comprensione: \u201cBompiani\u201d e \u201cIl pensiero occidentale\u201d, in contrapposizione evidente a quello orientale. Quindi gli abitanti della terra hanno ben due pensieri. \u201cDevono essere pensierosi assai\u201d, penser\u00e0 il l\u2019occhiuto extraterrestre, proprio poco prima che gli sovvenga che quel popolo pensieroso sta per essere distrutto dalla sua genia, non perch\u00e9 ne abbian voglia o bisogno (\u00e8 gente pacifica) ma perch\u00e9 cos\u00ec l\u2019umanit\u00e0 ha sempre pensato dei marziani e vedere esaudito un pensiero \u00e8 cosa gradita, e i marziani non vogliono essere sgradevoli.<\/p>\n<p id=\"225f\">La copertina \u00e8 prevalentemente bianca e il cibo dei marziani, curiosamente, \u00e8 sempre bianco. Tanto che l\u2019essere siderale porta l\u2019oggetto cartaceo alla bocca e se lo mangia.<br \/>\nFine.<\/p>","protected":false},"excerpt":{"rendered":"<p>Nel quale si analizza la copertina di una edizione a caso del suddetto libello<\/p>","protected":false},"author":1,"featured_media":33680,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[91],"tags":[308,307],"class_list":["post-33676","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura","tag-filosofia","tag-kant"],"acf":[],"_links":{"self":[{"href":"https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/posts\/33676","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/comments?post=33676"}],"version-history":[{"count":0,"href":"https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/posts\/33676\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/media\/33680"}],"wp:attachment":[{"href":"https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/media?parent=33676"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/categories?post=33676"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/tags?post=33676"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}