{"id":30132,"date":"2019-09-09T16:29:26","date_gmt":"2019-09-09T16:29:26","guid":{"rendered":"https:\/\/martinopietropoli.live-website.com\/?page_id=30132"},"modified":"2026-04-20T23:40:32","modified_gmt":"2026-04-20T23:40:32","slug":"artworks","status":"publish","type":"page","link":"https:\/\/martinopietropoli.com\/en\/artworks","title":{"rendered":"Art"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"30132\" class=\"elementor elementor-30132\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-79311bd elementor-section-content-middle elementor-section-full_width elementor-section-height-default elementor-section-height-default neuron-fixed-no\" data-id=\"79311bd\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9dae0f0\" data-id=\"9dae0f0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8390d5b elementor-section-boxed elementor-section-height-default elementor-section-height-default neuron-fixed-no\" data-id=\"8390d5b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-dc9d005\" data-id=\"dc9d005\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7b39a21\" data-id=\"7b39a21\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ba13d2b elementor-widget elementor-widget-heading\" data-id=\"ba13d2b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Art<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bf111fe elementor-widget elementor-widget-heading\" data-id=\"bf111fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Haute patisserie demands careful attention to ingredient quantities and cooking times. Drawing has no rules, only different techniques to convey something.  \nI could never replicate a piece exactly as the original because I would always seek its variation. I am not a pastry chef.<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b8587fd elementor-section-full_width elementor-section-height-default elementor-section-height-default neuron-fixed-no\" data-id=\"b8587fd\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-70786a9\" data-id=\"70786a9\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3481bdf elementor-widget elementor-widget-neuron-posts\" data-id=\"3481bdf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"neuron-posts.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"l-posts-wrapper l-filters-holder l-posts-wrapper--meta-outside h-overflow-hidden l-portfolio-wrapper\" data-posts=\"3481bdf\">\n\t\t\t<div class=\"m-filters\">\n    <ul id=\"filters\">\n                    <li class=\"active\" data-filter=\"*\"><a>Show All<\/a><\/li>\n                <li data-filter=\".abstract\"><a>Abstract<\/a><\/li><li data-filter=\".acquerelli\"><a>Watercolors<\/a><\/li><li data-filter=\".art\"><a>Art<\/a><\/li><li data-filter=\".exhibition\"><a>Exhibition<\/a><\/li><li data-filter=\".graphics\"><a>Graphics<\/a><\/li><li data-filter=\".illustration\"><a>Illustration<\/a><\/li><li data-filter=\".watercolor\"><a>Watercolor<\/a><\/li>    <\/ul>\n<\/div>\t\t\t\t\t\t<div class=\"l-portfolio-wrapper__items-holder l-portfolio-wrapper__items-holder--meta-outside h-overflow-hidden\">\n\t\t\t\t    <div class=\"row masonry\" data-masonry-id=\"5b077e7dec0e74fc761ce72f4a6565c7\">\n                                <div class=\"selector col-lg-6 graphics podcast-cover post-31434 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-graphics portfolio_category-podcast-cover\" data-id=\"31434\" data-columns=\"2-columns\">\n                <div class=\"o-post o-portfolio-item wow h-fadeInNeuron\" >\n                        <div class=\"o-neuron-hover\">\n        <div class=\"o-neuron-hover-holder\">\n            <div class=\"o-neuron-hover-holder__header\">\n                                    <a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/cammini\" class=\"o-neuron-hover-holder__header__media\">\n                                                    <div class=\"h-calculated-image\" style=\"padding-bottom: 100.000000% !important;\">\n                                <img fetchpriority=\"high\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/IMG_1491-500x500.jpg\" class=\"attachment-bifrost_image_size_1 size-bifrost_image_size_1 wp-post-image\" alt=\"\" srcset=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/IMG_1491-500x500.jpg 500w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/IMG_1491-600x600.jpg 600w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/IMG_1491-150x150.jpg 150w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/IMG_1491-300x300.jpg 300w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/IMG_1491-768x768.jpg 768w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/IMG_1491-1024x1024.jpg 1024w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/IMG_1491-1000x1000.jpg 1000w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/IMG_1491-100x100.jpg 100w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>                            <\/div>\n                                            <\/a>\n                                            <\/div>\n                    <\/div>\n    <\/div>\n<div class=\"o-portfolio-item__content o-neuron-post__content\">\n            <h5 class=\"o-portfolio-item__title o-neuron-post__title\"><a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/cammini\">Cammini<\/a><\/h5>\n        <\/div>                <\/div>\n            <\/div>\n                                <div class=\"selector col-lg-6 art featured_art posters post-35380 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-art portfolio_category-featured_art portfolio_category-posters\" data-id=\"35380\" data-columns=\"2-columns\">\n                <div class=\"o-post o-portfolio-item wow h-fadeInNeuron\" >\n                        <div class=\"o-neuron-hover\">\n        <div class=\"o-neuron-hover-holder\">\n            <div class=\"o-neuron-hover-holder__header\">\n                                    <a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/re-design-poster-design-italiano\" class=\"o-neuron-hover-holder__header__media\">\n                                                    <div class=\"h-calculated-image\" style=\"padding-bottom: 100.000000% !important;\">\n                                <img decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2022\/02\/ReDesign_cover-500x500.png\" class=\"attachment-bifrost_image_size_1 size-bifrost_image_size_1 wp-post-image\" alt=\"\" srcset=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2022\/02\/ReDesign_cover-500x500.png 500w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2022\/02\/ReDesign_cover-150x150.png 150w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2022\/02\/ReDesign_cover-12x12.png 12w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2022\/02\/ReDesign_cover-1000x1000.png 1000w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>                            <\/div>\n                                            <\/a>\n                                            <\/div>\n                    <\/div>\n    <\/div>\n<div class=\"o-portfolio-item__content o-neuron-post__content\">\n            <h5 class=\"o-portfolio-item__title o-neuron-post__title\"><a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/re-design-poster-design-italiano\">Re: Design<\/a><\/h5>\n        <\/div>                <\/div>\n            <\/div>\n                                <div class=\"selector col-lg-6 graphics podcast-cover post-31373 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-graphics portfolio_category-podcast-cover\" data-id=\"31373\" data-columns=\"2-columns\">\n                <div class=\"o-post o-portfolio-item wow h-fadeInNeuron\" >\n                        <div class=\"o-neuron-hover\">\n        <div class=\"o-neuron-hover-holder\">\n            <div class=\"o-neuron-hover-holder__header\">\n                                    <a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/laudionario\" class=\"o-neuron-hover-holder__header__media\">\n                                                    <div class=\"h-calculated-image\" style=\"padding-bottom: 100.000000% !important;\">\n                                <img decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/SLFM_2018119_Audionario_pillola_04-500x500.jpg\" class=\"attachment-bifrost_image_size_1 size-bifrost_image_size_1 wp-post-image\" alt=\"\" srcset=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/SLFM_2018119_Audionario_pillola_04-500x500.jpg 500w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/SLFM_2018119_Audionario_pillola_04-600x600.jpg 600w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/SLFM_2018119_Audionario_pillola_04-150x150.jpg 150w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/SLFM_2018119_Audionario_pillola_04-300x300.jpg 300w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/SLFM_2018119_Audionario_pillola_04-768x768.jpg 768w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/SLFM_2018119_Audionario_pillola_04-1024x1024.jpg 1024w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/SLFM_2018119_Audionario_pillola_04-1000x1000.jpg 1000w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/SLFM_2018119_Audionario_pillola_04-100x100.jpg 100w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/SLFM_2018119_Audionario_pillola_04.jpg 1797w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>                            <\/div>\n                                            <\/a>\n                                            <\/div>\n                    <\/div>\n    <\/div>\n<div class=\"o-portfolio-item__content o-neuron-post__content\">\n            <h5 class=\"o-portfolio-item__title o-neuron-post__title\"><a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/laudionario\">L&#8217;Audionario<\/a><\/h5>\n        <\/div>                <\/div>\n            <\/div>\n                                <div class=\"selector col-lg-6 graphics podcast-cover post-40801 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-graphics portfolio_category-podcast-cover\" data-id=\"40801\" data-columns=\"2-columns\">\n                <div class=\"o-post o-portfolio-item wow h-fadeInNeuron\" >\n                        <div class=\"o-neuron-hover\">\n        <div class=\"o-neuron-hover-holder\">\n            <div class=\"o-neuron-hover-holder__header\">\n                                    <a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/figli-del-carcere\" class=\"o-neuron-hover-holder__header__media\">\n                                                    <div class=\"h-calculated-image\" style=\"padding-bottom: 100.000000% !important;\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2023\/12\/SLFM_Figli_Del_Carcere_FIN_ALIKE-500x500.jpg\" class=\"attachment-bifrost_image_size_1 size-bifrost_image_size_1 wp-post-image\" alt=\"\" srcset=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2023\/12\/SLFM_Figli_Del_Carcere_FIN_ALIKE-500x500.jpg 500w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2023\/12\/SLFM_Figli_Del_Carcere_FIN_ALIKE-300x300.jpg 300w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2023\/12\/SLFM_Figli_Del_Carcere_FIN_ALIKE-1024x1024.jpg 1024w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2023\/12\/SLFM_Figli_Del_Carcere_FIN_ALIKE-150x150.jpg 150w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2023\/12\/SLFM_Figli_Del_Carcere_FIN_ALIKE-768x768.jpg 768w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2023\/12\/SLFM_Figli_Del_Carcere_FIN_ALIKE-1536x1536.jpg 1536w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2023\/12\/SLFM_Figli_Del_Carcere_FIN_ALIKE-12x12.jpg 12w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2023\/12\/SLFM_Figli_Del_Carcere_FIN_ALIKE-1000x1000.jpg 1000w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2023\/12\/SLFM_Figli_Del_Carcere_FIN_ALIKE.jpg 2048w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>                            <\/div>\n                                            <\/a>\n                                            <\/div>\n                    <\/div>\n    <\/div>\n<div class=\"o-portfolio-item__content o-neuron-post__content\">\n            <h5 class=\"o-portfolio-item__title o-neuron-post__title\"><a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/figli-del-carcere\">Figli del carcere<\/a><\/h5>\n        <\/div>                <\/div>\n            <\/div>\n                                <div class=\"selector col-lg-6 illustration post-31987 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-illustration\" data-id=\"31987\" data-columns=\"2-columns\">\n                <div class=\"o-post o-portfolio-item wow h-fadeInNeuron\" >\n                        <div class=\"o-neuron-hover\">\n        <div class=\"o-neuron-hover-holder\">\n            <div class=\"o-neuron-hover-holder__header\">\n                                    <a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/teotfw\" class=\"o-neuron-hover-holder__header__media\">\n                                                    <div class=\"h-calculated-image\" style=\"padding-bottom: 100.000000% !important;\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/11\/IMG_0009-500x500.jpg\" class=\"attachment-bifrost_image_size_1 size-bifrost_image_size_1 wp-post-image\" alt=\"\" srcset=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/11\/IMG_0009-500x500.jpg 500w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/11\/IMG_0009-150x150.jpg 150w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/11\/IMG_0009-1000x1000.jpg 1000w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>                            <\/div>\n                                            <\/a>\n                                            <\/div>\n                    <\/div>\n    <\/div>\n<div class=\"o-portfolio-item__content o-neuron-post__content\">\n            <h5 class=\"o-portfolio-item__title o-neuron-post__title\"><a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/teotfw\">The End of the F***ing World<\/a><\/h5>\n        <\/div>                <\/div>\n            <\/div>\n                                <div class=\"selector col-lg-6 art illustration post-31089 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-art portfolio_category-illustration\" data-id=\"31089\" data-columns=\"2-columns\">\n                <div class=\"o-post o-portfolio-item wow h-fadeInNeuron\" >\n                        <div class=\"o-neuron-hover\">\n        <div class=\"o-neuron-hover-holder\">\n            <div class=\"o-neuron-hover-holder__header\">\n                                    <a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/amore\" class=\"o-neuron-hover-holder__header__media\">\n                                                    <div class=\"h-calculated-image\" style=\"padding-bottom: 100.000000% !important;\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/IMG_1143-500x500.jpg\" class=\"attachment-bifrost_image_size_1 size-bifrost_image_size_1 wp-post-image\" alt=\"\" srcset=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/IMG_1143-500x500.jpg 500w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/IMG_1143-150x150.jpg 150w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/IMG_1143-1000x1000.jpg 1000w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/IMG_1143-300x300.jpg 300w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/IMG_1143-100x100.jpg 100w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>                            <\/div>\n                                            <\/a>\n                                            <\/div>\n                    <\/div>\n    <\/div>\n<div class=\"o-portfolio-item__content o-neuron-post__content\">\n            <h5 class=\"o-portfolio-item__title o-neuron-post__title\"><a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/amore\">Love<\/a><\/h5>\n        <\/div>                <\/div>\n            <\/div>\n                                <div class=\"selector col-lg-6 abstract art featured_art post-34222 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-abstract portfolio_category-art portfolio_category-featured_art\" data-id=\"34222\" data-columns=\"2-columns\">\n                <div class=\"o-post o-portfolio-item wow h-fadeInNeuron\" >\n                        <div class=\"o-neuron-hover\">\n        <div class=\"o-neuron-hover-holder\">\n            <div class=\"o-neuron-hover-holder__header\">\n                                    <a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/concrettes\" class=\"o-neuron-hover-holder__header__media\">\n                                                    <div class=\"h-calculated-image\" style=\"padding-bottom: 100.000000% !important;\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2020\/11\/Concrette-04-500x500.jpeg\" class=\"attachment-bifrost_image_size_1 size-bifrost_image_size_1 wp-post-image\" alt=\"\" srcset=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2020\/11\/Concrette-04-500x500.jpeg 500w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2020\/11\/Concrette-04-150x150.jpeg 150w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2020\/11\/Concrette-04-1000x1000.jpeg 1000w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>                            <\/div>\n                                            <\/a>\n                                            <\/div>\n                    <\/div>\n    <\/div>\n<div class=\"o-portfolio-item__content o-neuron-post__content\">\n            <h5 class=\"o-portfolio-item__title o-neuron-post__title\"><a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/concrettes\">Concrettes<\/a><\/h5>\n        <\/div>                <\/div>\n            <\/div>\n                                <div class=\"selector col-lg-6 design graphics post-34754 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-design portfolio_category-graphics\" data-id=\"34754\" data-columns=\"2-columns\">\n                <div class=\"o-post o-portfolio-item wow h-fadeInNeuron\" >\n                        <div class=\"o-neuron-hover\">\n        <div class=\"o-neuron-hover-holder\">\n            <div class=\"o-neuron-hover-holder__header\">\n                                    <a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/grafiche-pasqua-ada-2021\" class=\"o-neuron-hover-holder__header__media\">\n                                                    <div class=\"h-calculated-image\" style=\"padding-bottom: 100.000000% !important;\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2021\/03\/IMG_0928-500x500.jpeg\" class=\"attachment-bifrost_image_size_1 size-bifrost_image_size_1 wp-post-image\" alt=\"\" srcset=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2021\/03\/IMG_0928-500x500.jpeg 500w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2021\/03\/IMG_0928-150x150.jpeg 150w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2021\/03\/IMG_0928-1000x1000.jpeg 1000w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>                            <\/div>\n                                            <\/a>\n                                            <\/div>\n                    <\/div>\n    <\/div>\n<div class=\"o-portfolio-item__content o-neuron-post__content\">\n            <h5 class=\"o-portfolio-item__title o-neuron-post__title\"><a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/grafiche-pasqua-ada-2021\">Grafiche Pasqua 2021 per ADA<\/a><\/h5>\n        <\/div>                <\/div>\n            <\/div>\n                                <div class=\"selector col-lg-6 design graphics post-34374 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-design portfolio_category-graphics\" data-id=\"34374\" data-columns=\"2-columns\">\n                <div class=\"o-post o-portfolio-item wow h-fadeInNeuron\" >\n                        <div class=\"o-neuron-hover\">\n        <div class=\"o-neuron-hover-holder\">\n            <div class=\"o-neuron-hover-holder__header\">\n                                    <a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/i-barattoli-di-natale-2020-per-ada\" class=\"o-neuron-hover-holder__header__media\">\n                                                    <div class=\"h-calculated-image\" style=\"padding-bottom: 100.000000% !important;\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2020\/12\/ADA_Barattolo_piccolo-500x500.jpeg\" class=\"attachment-bifrost_image_size_1 size-bifrost_image_size_1 wp-post-image\" alt=\"\" srcset=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2020\/12\/ADA_Barattolo_piccolo-500x500.jpeg 500w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2020\/12\/ADA_Barattolo_piccolo-150x150.jpeg 150w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2020\/12\/ADA_Barattolo_piccolo-1000x1000.jpeg 1000w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>                            <\/div>\n                                            <\/a>\n                                            <\/div>\n                    <\/div>\n    <\/div>\n<div class=\"o-portfolio-item__content o-neuron-post__content\">\n            <h5 class=\"o-portfolio-item__title o-neuron-post__title\"><a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/i-barattoli-di-natale-2020-per-ada\">Christmas 2020 Cans for ADA<\/a><\/h5>\n        <\/div>                <\/div>\n            <\/div>\n                                <div class=\"selector col-lg-6 graphics podcast-cover post-40863 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-graphics portfolio_category-podcast-cover\" data-id=\"40863\" data-columns=\"2-columns\">\n                <div class=\"o-post o-portfolio-item wow h-fadeInNeuron\" >\n                        <div class=\"o-neuron-hover\">\n        <div class=\"o-neuron-hover-holder\">\n            <div class=\"o-neuron-hover-holder__header\">\n                                    <a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/un-caffe-con-lassassino\" class=\"o-neuron-hover-holder__header__media\">\n                                                    <div class=\"h-calculated-image\" style=\"padding-bottom: 100.000000% !important;\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2024\/05\/SLFM_Caffe\u0300_Assassino_20240506_FIN-500x500.jpg\" class=\"attachment-bifrost_image_size_1 size-bifrost_image_size_1 wp-post-image\" alt=\"\" srcset=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2024\/05\/SLFM_Caffe\u0300_Assassino_20240506_FIN-500x500.jpg 500w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2024\/05\/SLFM_Caffe\u0300_Assassino_20240506_FIN-300x300.jpg 300w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2024\/05\/SLFM_Caffe\u0300_Assassino_20240506_FIN-1024x1024.jpg 1024w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2024\/05\/SLFM_Caffe\u0300_Assassino_20240506_FIN-150x150.jpg 150w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2024\/05\/SLFM_Caffe\u0300_Assassino_20240506_FIN-768x768.jpg 768w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2024\/05\/SLFM_Caffe\u0300_Assassino_20240506_FIN-1536x1536.jpg 1536w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2024\/05\/SLFM_Caffe\u0300_Assassino_20240506_FIN-12x12.jpg 12w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2024\/05\/SLFM_Caffe\u0300_Assassino_20240506_FIN-1000x1000.jpg 1000w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2024\/05\/SLFM_Caffe\u0300_Assassino_20240506_FIN.jpg 1772w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>                            <\/div>\n                                            <\/a>\n                                            <\/div>\n                    <\/div>\n    <\/div>\n<div class=\"o-portfolio-item__content o-neuron-post__content\">\n            <h5 class=\"o-portfolio-item__title o-neuron-post__title\"><a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/un-caffe-con-lassassino\">Un caff\u00e8 con l&#8217;assassino<\/a><\/h5>\n        <\/div>                <\/div>\n            <\/div>\n                                <div class=\"selector col-lg-6 graphics podcast-cover post-34513 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-graphics portfolio_category-podcast-cover\" data-id=\"34513\" data-columns=\"2-columns\">\n                <div class=\"o-post o-portfolio-item wow h-fadeInNeuron\" >\n                        <div class=\"o-neuron-hover\">\n        <div class=\"o-neuron-hover-holder\">\n            <div class=\"o-neuron-hover-holder__header\">\n                                    <a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/love-bombing-podcast-cover\" class=\"o-neuron-hover-holder__header__media\">\n                                                    <div class=\"h-calculated-image\" style=\"padding-bottom: 100.000000% !important;\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2020\/12\/SLFM_Love_Bombing_def-500x500.jpg\" class=\"attachment-bifrost_image_size_1 size-bifrost_image_size_1 wp-post-image\" alt=\"\" srcset=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2020\/12\/SLFM_Love_Bombing_def-500x500.jpg 500w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2020\/12\/SLFM_Love_Bombing_def-300x300.jpg 300w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2020\/12\/SLFM_Love_Bombing_def-1024x1024.jpg 1024w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2020\/12\/SLFM_Love_Bombing_def-150x150.jpg 150w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2020\/12\/SLFM_Love_Bombing_def-768x768.jpg 768w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2020\/12\/SLFM_Love_Bombing_def-1536x1536.jpg 1536w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2020\/12\/SLFM_Love_Bombing_def-12x12.jpg 12w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2020\/12\/SLFM_Love_Bombing_def-1000x1000.jpg 1000w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2020\/12\/SLFM_Love_Bombing_def.jpg 1800w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>                            <\/div>\n                                            <\/a>\n                                            <\/div>\n                    <\/div>\n    <\/div>\n<div class=\"o-portfolio-item__content o-neuron-post__content\">\n            <h5 class=\"o-portfolio-item__title o-neuron-post__title\"><a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/love-bombing-podcast-cover\">Love Bombing<\/a><\/h5>\n        <\/div>                <\/div>\n            <\/div>\n                                <div class=\"selector col-lg-6 art illustration post-31845 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-art portfolio_category-illustration\" data-id=\"31845\" data-columns=\"2-columns\">\n                <div class=\"o-post o-portfolio-item wow h-fadeInNeuron\" >\n                        <div class=\"o-neuron-hover\">\n        <div class=\"o-neuron-hover-holder\">\n            <div class=\"o-neuron-hover-holder__header\">\n                                    <a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/flora\" class=\"o-neuron-hover-holder__header__media\">\n                                                    <div class=\"h-calculated-image\" style=\"padding-bottom: 100.000000% !important;\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/11\/30829FF8-8354-400E-AA9C-C36B45DAE455-500x500.jpeg\" class=\"attachment-bifrost_image_size_1 size-bifrost_image_size_1 wp-post-image\" alt=\"\" srcset=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/11\/30829FF8-8354-400E-AA9C-C36B45DAE455-500x500.jpeg 500w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/11\/30829FF8-8354-400E-AA9C-C36B45DAE455-150x150.jpeg 150w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/11\/30829FF8-8354-400E-AA9C-C36B45DAE455-1000x1000.jpeg 1000w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/11\/30829FF8-8354-400E-AA9C-C36B45DAE455-300x300.jpeg 300w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/11\/30829FF8-8354-400E-AA9C-C36B45DAE455-100x100.jpeg 100w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>                            <\/div>\n                                            <\/a>\n                                            <\/div>\n                    <\/div>\n    <\/div>\n<div class=\"o-portfolio-item__content o-neuron-post__content\">\n            <h5 class=\"o-portfolio-item__title o-neuron-post__title\"><a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/flora\">Flora<\/a><\/h5>\n        <\/div>                <\/div>\n            <\/div>\n                                <div class=\"selector col-lg-6 design graphics illustration post-34027 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-design portfolio_category-graphics portfolio_category-illustration\" data-id=\"34027\" data-columns=\"2-columns\">\n                <div class=\"o-post o-portfolio-item wow h-fadeInNeuron\" >\n                        <div class=\"o-neuron-hover\">\n        <div class=\"o-neuron-hover-holder\">\n            <div class=\"o-neuron-hover-holder__header\">\n                                    <a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/designers-against-coronavirus\" class=\"o-neuron-hover-holder__header__media\">\n                                                    <div class=\"h-calculated-image\" style=\"padding-bottom: 100.000000% !important;\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2020\/04\/DAC-1-500x500.jpg\" class=\"attachment-bifrost_image_size_1 size-bifrost_image_size_1 wp-post-image\" alt=\"\" srcset=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2020\/04\/DAC-1-500x500.jpg 500w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2020\/04\/DAC-1-300x300.jpg 300w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2020\/04\/DAC-1-1024x1024.jpg 1024w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2020\/04\/DAC-1-150x150.jpg 150w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2020\/04\/DAC-1-768x768.jpg 768w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2020\/04\/DAC-1-12x12.jpg 12w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2020\/04\/DAC-1-1000x1000.jpg 1000w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2020\/04\/DAC-1.jpg 1396w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>                            <\/div>\n                                            <\/a>\n                                            <\/div>\n                    <\/div>\n    <\/div>\n<div class=\"o-portfolio-item__content o-neuron-post__content\">\n            <h5 class=\"o-portfolio-item__title o-neuron-post__title\"><a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/designers-against-coronavirus\">Designers Against Coronavirus<\/a><\/h5>\n        <\/div>                <\/div>\n            <\/div>\n                                <div class=\"selector col-lg-6 art books libri photography post-33715 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-art portfolio_category-books portfolio_category-libri portfolio_category-photography\" data-id=\"33715\" data-columns=\"2-columns\">\n                <div class=\"o-post o-portfolio-item wow h-fadeInNeuron\" >\n                        <div class=\"o-neuron-hover\">\n        <div class=\"o-neuron-hover-holder\">\n            <div class=\"o-neuron-hover-holder__header\">\n                                    <a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/martino-pietropoli-on-martino-pietropoli\" class=\"o-neuron-hover-holder__header__media\">\n                                                    <div class=\"h-calculated-image\" style=\"padding-bottom: 100.000000% !important;\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2020\/02\/MP_Portfolio_00-500x500.jpg\" class=\"attachment-bifrost_image_size_1 size-bifrost_image_size_1 wp-post-image\" alt=\"\" srcset=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2020\/02\/MP_Portfolio_00-500x500.jpg 500w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2020\/02\/MP_Portfolio_00-150x150.jpg 150w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2020\/02\/MP_Portfolio_00-1000x1000.jpg 1000w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>                            <\/div>\n                                            <\/a>\n                                            <\/div>\n                    <\/div>\n    <\/div>\n<div class=\"o-portfolio-item__content o-neuron-post__content\">\n            <h5 class=\"o-portfolio-item__title o-neuron-post__title\"><a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/martino-pietropoli-on-martino-pietropoli\">Martino Pietropoli on Martino Pietropoli<\/a><\/h5>\n        <\/div>                <\/div>\n            <\/div>\n                                <div class=\"selector col-lg-6 art graphics post-31032 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-art portfolio_category-graphics\" data-id=\"31032\" data-columns=\"2-columns\">\n                <div class=\"o-post o-portfolio-item wow h-fadeInNeuron\" >\n                        <div class=\"o-neuron-hover\">\n        <div class=\"o-neuron-hover-holder\">\n            <div class=\"o-neuron-hover-holder__header\">\n                                    <a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/mani\" class=\"o-neuron-hover-holder__header__media\">\n                                                    <div class=\"h-calculated-image\" style=\"padding-bottom: 100.000000% !important;\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/IMG_1348-500x500.jpg\" class=\"attachment-bifrost_image_size_1 size-bifrost_image_size_1 wp-post-image\" alt=\"\" srcset=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/IMG_1348-500x500.jpg 500w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/IMG_1348-150x150.jpg 150w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/IMG_1348-1000x1000.jpg 1000w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/IMG_1348-300x300.jpg 300w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/IMG_1348-100x100.jpg 100w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>                            <\/div>\n                                            <\/a>\n                                            <\/div>\n                    <\/div>\n    <\/div>\n<div class=\"o-portfolio-item__content o-neuron-post__content\">\n            <h5 class=\"o-portfolio-item__title o-neuron-post__title\"><a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/mani\">Hands<\/a><\/h5>\n        <\/div>                <\/div>\n            <\/div>\n                                <div class=\"selector col-lg-6 art featured_art posters post-35410 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-art portfolio_category-featured_art portfolio_category-posters\" data-id=\"35410\" data-columns=\"2-columns\">\n                <div class=\"o-post o-portfolio-item wow h-fadeInNeuron\" >\n                        <div class=\"o-neuron-hover\">\n        <div class=\"o-neuron-hover-holder\">\n            <div class=\"o-neuron-hover-holder__header\">\n                                    <a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/superminimal-poster-minimalism\" class=\"o-neuron-hover-holder__header__media\">\n                                                    <div class=\"h-calculated-image\" style=\"padding-bottom: 100.000000% !important;\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2022\/02\/Schermata-2022-02-14-alle-11.16.04-500x500.png\" class=\"attachment-bifrost_image_size_1 size-bifrost_image_size_1 wp-post-image\" alt=\"\" srcset=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2022\/02\/Schermata-2022-02-14-alle-11.16.04-500x500.png 500w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2022\/02\/Schermata-2022-02-14-alle-11.16.04-150x150.png 150w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2022\/02\/Schermata-2022-02-14-alle-11.16.04-12x12.png 12w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2022\/02\/Schermata-2022-02-14-alle-11.16.04-1000x1000.png 1000w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>                            <\/div>\n                                            <\/a>\n                                            <\/div>\n                    <\/div>\n    <\/div>\n<div class=\"o-portfolio-item__content o-neuron-post__content\">\n            <h5 class=\"o-portfolio-item__title o-neuron-post__title\"><a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/superminimal-poster-minimalism\">Superminimal<\/a><\/h5>\n        <\/div>                <\/div>\n            <\/div>\n                                <div class=\"selector col-lg-6 graphics podcast-cover post-31819 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-graphics portfolio_category-podcast-cover\" data-id=\"31819\" data-columns=\"2-columns\">\n                <div class=\"o-post o-portfolio-item wow h-fadeInNeuron\" >\n                        <div class=\"o-neuron-hover\">\n        <div class=\"o-neuron-hover-holder\">\n            <div class=\"o-neuron-hover-holder__header\">\n                                    <a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/le-regole-dellamore\" class=\"o-neuron-hover-holder__header__media\">\n                                                    <div class=\"h-calculated-image\" style=\"padding-bottom: 100.000000% !important;\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/SLFM_20190415_Regole_Amore-500x500.png\" class=\"attachment-bifrost_image_size_1 size-bifrost_image_size_1 wp-post-image\" alt=\"\" srcset=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/SLFM_20190415_Regole_Amore-500x500.png 500w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/SLFM_20190415_Regole_Amore-150x150.png 150w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/SLFM_20190415_Regole_Amore-300x300.png 300w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/SLFM_20190415_Regole_Amore-768x768.png 768w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/SLFM_20190415_Regole_Amore-1024x1024.png 1024w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/SLFM_20190415_Regole_Amore-1000x1000.png 1000w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/SLFM_20190415_Regole_Amore-600x600.png 600w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/SLFM_20190415_Regole_Amore-100x100.png 100w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>                            <\/div>\n                                            <\/a>\n                                            <\/div>\n                    <\/div>\n    <\/div>\n<div class=\"o-portfolio-item__content o-neuron-post__content\">\n            <h5 class=\"o-portfolio-item__title o-neuron-post__title\"><a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/le-regole-dellamore\">Le regole dell&#8217;amore<\/a><\/h5>\n        <\/div>                <\/div>\n            <\/div>\n                                <div class=\"selector col-lg-6 art featured_art illustration post-31408 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-art portfolio_category-featured_art portfolio_category-illustration\" data-id=\"31408\" data-columns=\"2-columns\">\n                <div class=\"o-post o-portfolio-item wow h-fadeInNeuron\" >\n                        <div class=\"o-neuron-hover\">\n        <div class=\"o-neuron-hover-holder\">\n            <div class=\"o-neuron-hover-holder__header\">\n                                    <a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/send-nudes\" class=\"o-neuron-hover-holder__header__media\">\n                                                    <div class=\"h-calculated-image\" style=\"padding-bottom: 100.000000% !important;\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/IMG_1372-500x500.jpg\" class=\"attachment-bifrost_image_size_1 size-bifrost_image_size_1 wp-post-image\" alt=\"\" srcset=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/IMG_1372-500x500.jpg 500w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/IMG_1372-150x150.jpg 150w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/IMG_1372-1000x1000.jpg 1000w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/IMG_1372-300x300.jpg 300w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/IMG_1372-100x100.jpg 100w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>                            <\/div>\n                                            <\/a>\n                                            <\/div>\n                    <\/div>\n    <\/div>\n<div class=\"o-portfolio-item__content o-neuron-post__content\">\n            <h5 class=\"o-portfolio-item__title o-neuron-post__title\"><a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/send-nudes\">Send nudes<\/a><\/h5>\n        <\/div>                <\/div>\n            <\/div>\n                                <div class=\"selector col-lg-6 graphics podcast-cover post-34117 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-graphics portfolio_category-podcast-cover\" data-id=\"34117\" data-columns=\"2-columns\">\n                <div class=\"o-post o-portfolio-item wow h-fadeInNeuron\" >\n                        <div class=\"o-neuron-hover\">\n        <div class=\"o-neuron-hover-holder\">\n            <div class=\"o-neuron-hover-holder__header\">\n                                    <a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/ifi-informatic-forensic-investigation\" class=\"o-neuron-hover-holder__header__media\">\n                                                    <div class=\"h-calculated-image\" style=\"padding-bottom: 100.000000% !important;\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2020\/09\/SLFM_IFI_20200902_01-500x500.jpg\" class=\"attachment-bifrost_image_size_1 size-bifrost_image_size_1 wp-post-image\" alt=\"\" srcset=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2020\/09\/SLFM_IFI_20200902_01-500x500.jpg 500w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2020\/09\/SLFM_IFI_20200902_01-300x300.jpg 300w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2020\/09\/SLFM_IFI_20200902_01-1024x1024.jpg 1024w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2020\/09\/SLFM_IFI_20200902_01-150x150.jpg 150w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2020\/09\/SLFM_IFI_20200902_01-768x768.jpg 768w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2020\/09\/SLFM_IFI_20200902_01-1536x1536.jpg 1536w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2020\/09\/SLFM_IFI_20200902_01-2048x2048.jpg 2048w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2020\/09\/SLFM_IFI_20200902_01-1000x1000.jpg 1000w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>                            <\/div>\n                                            <\/a>\n                                            <\/div>\n                    <\/div>\n    <\/div>\n<div class=\"o-portfolio-item__content o-neuron-post__content\">\n            <h5 class=\"o-portfolio-item__title o-neuron-post__title\"><a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/ifi-informatic-forensic-investigation\">IFI &#8211; Informatic Forensic Investigation<\/a><\/h5>\n        <\/div>                <\/div>\n            <\/div>\n                                <div class=\"selector col-lg-6 art illustration post-30878 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-art portfolio_category-illustration\" data-id=\"30878\" data-columns=\"2-columns\">\n                <div class=\"o-post o-portfolio-item wow h-fadeInNeuron\" >\n                        <div class=\"o-neuron-hover\">\n        <div class=\"o-neuron-hover-holder\">\n            <div class=\"o-neuron-hover-holder__header\">\n                                    <a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/esile-2\" class=\"o-neuron-hover-holder__header__media\">\n                                                    <div class=\"h-calculated-image\" style=\"padding-bottom: 100.000000% !important;\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/IMG_0001-500x500.jpg\" class=\"attachment-bifrost_image_size_1 size-bifrost_image_size_1 wp-post-image\" alt=\"\" srcset=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/IMG_0001-500x500.jpg 500w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/IMG_0001-150x150.jpg 150w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/IMG_0001-1000x1000.jpg 1000w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/IMG_0001-300x300.jpg 300w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/IMG_0001-100x100.jpg 100w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>                            <\/div>\n                                            <\/a>\n                                            <\/div>\n                    <\/div>\n    <\/div>\n<div class=\"o-portfolio-item__content o-neuron-post__content\">\n            <h5 class=\"o-portfolio-item__title o-neuron-post__title\"><a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/esile-2\">Eternal Sunshine of the Spotless Mind<\/a><\/h5>\n        <\/div>                <\/div>\n            <\/div>\n                                <div class=\"selector col-lg-6 art featured_art illustration post-34544 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-art portfolio_category-featured_art portfolio_category-illustration\" data-id=\"34544\" data-columns=\"2-columns\">\n                <div class=\"o-post o-portfolio-item wow h-fadeInNeuron\" >\n                        <div class=\"o-neuron-hover\">\n        <div class=\"o-neuron-hover-holder\">\n            <div class=\"o-neuron-hover-holder__header\">\n                                    <a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/la-notte-michelangelo-antonioni\" class=\"o-neuron-hover-holder__header__media\">\n                                                    <div class=\"h-calculated-image\" style=\"padding-bottom: 100.000000% !important;\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2021\/01\/IMG_1740-500x500.jpg\" class=\"attachment-bifrost_image_size_1 size-bifrost_image_size_1 wp-post-image\" alt=\"\" srcset=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2021\/01\/IMG_1740-500x500.jpg 500w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2021\/01\/IMG_1740-150x150.jpg 150w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2021\/01\/IMG_1740-1000x1000.jpg 1000w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>                            <\/div>\n                                            <\/a>\n                                            <\/div>\n                    <\/div>\n    <\/div>\n<div class=\"o-portfolio-item__content o-neuron-post__content\">\n            <h5 class=\"o-portfolio-item__title o-neuron-post__title\"><a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/la-notte-michelangelo-antonioni\">La Notte<\/a><\/h5>\n        <\/div>                <\/div>\n            <\/div>\n                                <div class=\"selector col-lg-6 graphics podcast-cover post-28618 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-graphics portfolio_category-podcast-cover\" data-id=\"28618\" data-columns=\"2-columns\">\n                <div class=\"o-post o-portfolio-item wow h-fadeInNeuron\" >\n                        <div class=\"o-neuron-hover\">\n        <div class=\"o-neuron-hover-holder\">\n            <div class=\"o-neuron-hover-holder__header\">\n                                    <a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/soli-osho\" class=\"o-neuron-hover-holder__header__media\">\n                                                    <div class=\"h-calculated-image\" style=\"padding-bottom: 100.000000% !important;\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/07\/SLFM_Alone_20181228c-500x500.jpg\" class=\"attachment-bifrost_image_size_1 size-bifrost_image_size_1 wp-post-image\" alt=\"\" srcset=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/07\/SLFM_Alone_20181228c-500x500.jpg 500w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/07\/SLFM_Alone_20181228c-150x150.jpg 150w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/07\/SLFM_Alone_20181228c-300x300.jpg 300w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/07\/SLFM_Alone_20181228c-768x768.jpg 768w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/07\/SLFM_Alone_20181228c-1024x1024.jpg 1024w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/07\/SLFM_Alone_20181228c-1000x1000.jpg 1000w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/07\/SLFM_Alone_20181228c-600x600.jpg 600w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/07\/SLFM_Alone_20181228c-100x100.jpg 100w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>                            <\/div>\n                                            <\/a>\n                                            <\/div>\n                    <\/div>\n    <\/div>\n<div class=\"o-portfolio-item__content o-neuron-post__content\">\n            <h5 class=\"o-portfolio-item__title o-neuron-post__title\"><a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/soli-osho\">Soli &#8211; I bambini di Osho<\/a><\/h5>\n        <\/div>                <\/div>\n            <\/div>\n                                <div class=\"selector col-lg-6 acquerelli art watercolor post-41481 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-acquerelli portfolio_category-art portfolio_category-watercolor\" data-id=\"41481\" data-columns=\"2-columns\">\n                <div class=\"o-post o-portfolio-item wow h-fadeInNeuron\" >\n                        <div class=\"o-neuron-hover\">\n        <div class=\"o-neuron-hover-holder\">\n            <div class=\"o-neuron-hover-holder__header\">\n                                    <a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/petali\" class=\"o-neuron-hover-holder__header__media\">\n                                                    <div class=\"h-calculated-image\" style=\"padding-bottom: 100.000000% !important;\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2025\/04\/FCF02535-7189-401B-B0D4-F0CE8DE90AD4-500x500.jpg\" class=\"attachment-bifrost_image_size_1 size-bifrost_image_size_1 wp-post-image\" alt=\"\" srcset=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2025\/04\/FCF02535-7189-401B-B0D4-F0CE8DE90AD4-500x500.jpg 500w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2025\/04\/FCF02535-7189-401B-B0D4-F0CE8DE90AD4-150x150.jpg 150w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2025\/04\/FCF02535-7189-401B-B0D4-F0CE8DE90AD4-1000x1000.jpg 1000w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>                            <\/div>\n                                            <\/a>\n                                            <\/div>\n                    <\/div>\n    <\/div>\n<div class=\"o-portfolio-item__content o-neuron-post__content\">\n            <h5 class=\"o-portfolio-item__title o-neuron-post__title\"><a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/petali\">Petali<\/a><\/h5>\n        <\/div>                <\/div>\n            <\/div>\n                                <div class=\"selector col-lg-6 graphics podcast-cover post-33531 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-graphics portfolio_category-podcast-cover\" data-id=\"33531\" data-columns=\"2-columns\">\n                <div class=\"o-post o-portfolio-item wow h-fadeInNeuron\" >\n                        <div class=\"o-neuron-hover\">\n        <div class=\"o-neuron-hover-holder\">\n            <div class=\"o-neuron-hover-holder__header\">\n                                    <a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/radici\" class=\"o-neuron-hover-holder__header__media\">\n                                                    <div class=\"h-calculated-image\" style=\"padding-bottom: 100.000000% !important;\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2020\/01\/SLFM_Radici_03-500x500.png\" class=\"attachment-bifrost_image_size_1 size-bifrost_image_size_1 wp-post-image\" alt=\"\" srcset=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2020\/01\/SLFM_Radici_03-500x500.png 500w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2020\/01\/SLFM_Radici_03-300x300.png 300w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2020\/01\/SLFM_Radici_03-1024x1024.png 1024w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2020\/01\/SLFM_Radici_03-150x150.png 150w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2020\/01\/SLFM_Radici_03-768x769.png 768w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2020\/01\/SLFM_Radici_03-1000x1000.png 1000w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2020\/01\/SLFM_Radici_03.png 1374w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>                            <\/div>\n                                            <\/a>\n                                            <\/div>\n                    <\/div>\n    <\/div>\n<div class=\"o-portfolio-item__content o-neuron-post__content\">\n            <h5 class=\"o-portfolio-item__title o-neuron-post__title\"><a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/radici\">Radici<\/a><\/h5>\n        <\/div>                <\/div>\n            <\/div>\n                                <div class=\"selector col-lg-6 graphics podcast-cover post-35452 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-graphics portfolio_category-podcast-cover\" data-id=\"35452\" data-columns=\"2-columns\">\n                <div class=\"o-post o-portfolio-item wow h-fadeInNeuron\" >\n                        <div class=\"o-neuron-hover\">\n        <div class=\"o-neuron-hover-holder\">\n            <div class=\"o-neuron-hover-holder__header\">\n                                    <a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/alfabeto-italiano-podcast-cover\" class=\"o-neuron-hover-holder__header__media\">\n                                                    <div class=\"h-calculated-image\" style=\"padding-bottom: 100.000000% !important;\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2022\/06\/SLFM_Alfabeto_Italiano_FINALE-500x500.jpg\" class=\"attachment-bifrost_image_size_1 size-bifrost_image_size_1 wp-post-image\" alt=\"\" srcset=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2022\/06\/SLFM_Alfabeto_Italiano_FINALE-500x500.jpg 500w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2022\/06\/SLFM_Alfabeto_Italiano_FINALE-300x300.jpg 300w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2022\/06\/SLFM_Alfabeto_Italiano_FINALE-1024x1024.jpg 1024w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2022\/06\/SLFM_Alfabeto_Italiano_FINALE-150x150.jpg 150w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2022\/06\/SLFM_Alfabeto_Italiano_FINALE-768x768.jpg 768w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2022\/06\/SLFM_Alfabeto_Italiano_FINALE-1536x1536.jpg 1536w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2022\/06\/SLFM_Alfabeto_Italiano_FINALE-2048x2048.jpg 2048w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2022\/06\/SLFM_Alfabeto_Italiano_FINALE-12x12.jpg 12w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2022\/06\/SLFM_Alfabeto_Italiano_FINALE-1000x1000.jpg 1000w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>                            <\/div>\n                                            <\/a>\n                                            <\/div>\n                    <\/div>\n    <\/div>\n<div class=\"o-portfolio-item__content o-neuron-post__content\">\n            <h5 class=\"o-portfolio-item__title o-neuron-post__title\"><a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/alfabeto-italiano-podcast-cover\">Alfabeto Italiano<\/a><\/h5>\n        <\/div>                <\/div>\n            <\/div>\n                                <div class=\"selector col-lg-6 art illustration post-30843 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-art portfolio_category-illustration\" data-id=\"30843\" data-columns=\"2-columns\">\n                <div class=\"o-post o-portfolio-item wow h-fadeInNeuron\" >\n                        <div class=\"o-neuron-hover\">\n        <div class=\"o-neuron-hover-holder\">\n            <div class=\"o-neuron-hover-holder__header\">\n                                    <a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/lavventura\" class=\"o-neuron-hover-holder__header__media\">\n                                                    <div class=\"h-calculated-image\" style=\"padding-bottom: 100.000000% !important;\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/IMG_1520-500x500.jpg\" class=\"attachment-bifrost_image_size_1 size-bifrost_image_size_1 wp-post-image\" alt=\"\" srcset=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/IMG_1520-500x500.jpg 500w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/IMG_1520-150x150.jpg 150w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/IMG_1520-1000x1000.jpg 1000w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/IMG_1520-300x300.jpg 300w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/IMG_1520-100x100.jpg 100w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>                            <\/div>\n                                            <\/a>\n                                            <\/div>\n                    <\/div>\n    <\/div>\n<div class=\"o-portfolio-item__content o-neuron-post__content\">\n            <h5 class=\"o-portfolio-item__title o-neuron-post__title\"><a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/lavventura\">L&#8217;Avventura<\/a><\/h5>\n        <\/div>                <\/div>\n            <\/div>\n                                <div class=\"selector col-lg-6 books graphics illustration libri post-34602 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-books portfolio_category-graphics portfolio_category-illustration portfolio_category-libri\" data-id=\"34602\" data-columns=\"2-columns\">\n                <div class=\"o-post o-portfolio-item wow h-fadeInNeuron\" >\n                        <div class=\"o-neuron-hover\">\n        <div class=\"o-neuron-hover-holder\">\n            <div class=\"o-neuron-hover-holder__header\">\n                                    <a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/fedrigoni-365\" class=\"o-neuron-hover-holder__header__media\">\n                                                    <div class=\"h-calculated-image\" style=\"padding-bottom: 100.000000% !important;\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2021\/01\/IMG_0102-500x500.jpg\" class=\"attachment-bifrost_image_size_1 size-bifrost_image_size_1 wp-post-image\" alt=\"\" srcset=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2021\/01\/IMG_0102-500x500.jpg 500w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2021\/01\/IMG_0102-150x150.jpg 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>                            <\/div>\n                                            <\/a>\n                                            <\/div>\n                    <\/div>\n    <\/div>\n<div class=\"o-portfolio-item__content o-neuron-post__content\">\n            <h5 class=\"o-portfolio-item__title o-neuron-post__title\"><a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/fedrigoni-365\">Fedrigoni 365<\/a><\/h5>\n        <\/div>                <\/div>\n            <\/div>\n                                <div class=\"selector col-lg-6 art featured_art graphics illustration posters post-34976 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-art portfolio_category-featured_art portfolio_category-graphics portfolio_category-illustration portfolio_category-posters\" data-id=\"34976\" data-columns=\"2-columns\">\n                <div class=\"o-post o-portfolio-item wow h-fadeInNeuron\" >\n                        <div class=\"o-neuron-hover\">\n        <div class=\"o-neuron-hover-holder\">\n            <div class=\"o-neuron-hover-holder__header\">\n                                    <a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/poster-collection-10co\" class=\"o-neuron-hover-holder__header__media\">\n                                                    <div class=\"h-calculated-image\" style=\"padding-bottom: 100.000000% !important;\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2021\/07\/10CO-1_FRAME-500x500.jpg\" class=\"attachment-bifrost_image_size_1 size-bifrost_image_size_1 wp-post-image\" alt=\"\" srcset=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2021\/07\/10CO-1_FRAME-500x500.jpg 500w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2021\/07\/10CO-1_FRAME-300x300.jpg 300w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2021\/07\/10CO-1_FRAME-1024x1024.jpg 1024w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2021\/07\/10CO-1_FRAME-150x150.jpg 150w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2021\/07\/10CO-1_FRAME-768x768.jpg 768w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2021\/07\/10CO-1_FRAME-1536x1536.jpg 1536w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2021\/07\/10CO-1_FRAME-2048x2048.jpg 2048w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2021\/07\/10CO-1_FRAME-12x12.jpg 12w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2021\/07\/10CO-1_FRAME-1000x1000.jpg 1000w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>                            <\/div>\n                                            <\/a>\n                                            <\/div>\n                    <\/div>\n    <\/div>\n<div class=\"o-portfolio-item__content o-neuron-post__content\">\n            <h5 class=\"o-portfolio-item__title o-neuron-post__title\"><a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/poster-collection-10co\">10CO, The Poster Collection<\/a><\/h5>\n        <\/div>                <\/div>\n            <\/div>\n                                <div class=\"selector col-lg-6 abstract art featured_art post-32236 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-abstract portfolio_category-art portfolio_category-featured_art\" data-id=\"32236\" data-columns=\"2-columns\">\n                <div class=\"o-post o-portfolio-item wow h-fadeInNeuron\" >\n                        <div class=\"o-neuron-hover\">\n        <div class=\"o-neuron-hover-holder\">\n            <div class=\"o-neuron-hover-holder__header\">\n                                    <a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/ritorni\" class=\"o-neuron-hover-holder__header__media\">\n                                                    <div class=\"h-calculated-image\" style=\"padding-bottom: 100.000000% !important;\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/11\/MP_CB_13-500x500.jpg\" class=\"attachment-bifrost_image_size_1 size-bifrost_image_size_1 wp-post-image\" alt=\"\" srcset=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/11\/MP_CB_13-500x500.jpg 500w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/11\/MP_CB_13-150x150.jpg 150w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/11\/MP_CB_13-1000x1000.jpg 1000w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>                            <\/div>\n                                            <\/a>\n                                            <\/div>\n                    <\/div>\n    <\/div>\n<div class=\"o-portfolio-item__content o-neuron-post__content\">\n            <h5 class=\"o-portfolio-item__title o-neuron-post__title\"><a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/ritorni\">Recurrence<\/a><\/h5>\n        <\/div>                <\/div>\n            <\/div>\n                                <div class=\"selector col-lg-6 abstract art featured_art post-41086 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-abstract portfolio_category-art portfolio_category-featured_art\" data-id=\"41086\" data-columns=\"2-columns\">\n                <div class=\"o-post o-portfolio-item wow h-fadeInNeuron\" >\n                        <div class=\"o-neuron-hover\">\n        <div class=\"o-neuron-hover-holder\">\n            <div class=\"o-neuron-hover-holder__header\">\n                                    <a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/le-cose-fragile\" class=\"o-neuron-hover-holder__header__media\">\n                                                    <div class=\"h-calculated-image\" style=\"padding-bottom: 100.000000% !important;\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2024\/11\/Le-Cose-Fragili-02-Pass-500x500.jpg\" class=\"attachment-bifrost_image_size_1 size-bifrost_image_size_1 wp-post-image\" alt=\"\" srcset=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2024\/11\/Le-Cose-Fragili-02-Pass-500x500.jpg 500w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2024\/11\/Le-Cose-Fragili-02-Pass-300x300.jpg 300w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2024\/11\/Le-Cose-Fragili-02-Pass-1024x1024.jpg 1024w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2024\/11\/Le-Cose-Fragili-02-Pass-150x150.jpg 150w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2024\/11\/Le-Cose-Fragili-02-Pass-768x768.jpg 768w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2024\/11\/Le-Cose-Fragili-02-Pass-1536x1536.jpg 1536w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2024\/11\/Le-Cose-Fragili-02-Pass-12x12.jpg 12w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2024\/11\/Le-Cose-Fragili-02-Pass-1000x1000.jpg 1000w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2024\/11\/Le-Cose-Fragili-02-Pass.jpg 2048w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>                            <\/div>\n                                            <\/a>\n                                            <\/div>\n                    <\/div>\n    <\/div>\n<div class=\"o-portfolio-item__content o-neuron-post__content\">\n            <h5 class=\"o-portfolio-item__title o-neuron-post__title\"><a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/le-cose-fragile\">Le cose fragili<\/a><\/h5>\n        <\/div>                <\/div>\n            <\/div>\n            <\/div>\n\n\n<div class='o-pagination'><div class='container'><div class='row align-items-center h-medium-top-padding h-medium-bottom-padding'><div class='o-pagination__arrow d-inline-flex col-2 o-pagination__arrow--disabled'><a class=\"bifrost-link d-inline-flex\" href='https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/pages\/30132'><svg xmlns='http:\/\/www.w3.org\/2000\/svg' width='22' height='22' viewbox='0 0 24 24' fill='none' stroke-width='2' stroke-linecap='round' stroke-linejoin='round' class='feather feather-chevron-left'><polyline points='15 18 9 12 15 6'><\/polyline><\/svg><\/a><\/div><ul class='col-8 h-align-center o-pagination__numbers'><li class=\"active\"><a>1<\/a><\/li><li><a href='https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/pages\/30132\/page\/2' class=\"inactive bifrost-link\">2<\/a><\/li><\/ul><div class='o-pagination__arrow d-inline-flex col-2'><a class=\"bifrost-link d-inline-flex ml-auto\" href='https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/pages\/30132\/page\/2'><svg xmlns='http:\/\/www.w3.org\/2000\/svg' width='22' height='22' viewbox='0 0 24 24' fill='none' stroke-width='2' stroke-linecap='round' stroke-linejoin='round' class='feather feather-chevron-right'><polyline points='9 18 15 12 9 6'><\/polyline><\/svg><\/a><\/div><\/div><\/div><\/div>\n\n\n\t\t\t<\/div>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Arte L&#8217;alta pasticceria richiede un attento rispetto delle quantit\u00e0 degli ingredienti e dei tempi di cottura. Il disegno&#8230;<\/p>","protected":false},"author":1,"featured_media":32170,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-30132","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/pages\/30132","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/comments?post=30132"}],"version-history":[{"count":3,"href":"https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/pages\/30132\/revisions"}],"predecessor-version":[{"id":41798,"href":"https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/pages\/30132\/revisions\/41798"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/media\/32170"}],"wp:attachment":[{"href":"https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/media?parent=30132"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}