{"id":29866,"date":"2019-09-04T15:40:55","date_gmt":"2019-09-04T15:40:55","guid":{"rendered":"https:\/\/martinopietropoli.live-website.com\/?page_id=29866"},"modified":"2024-12-30T15:39:16","modified_gmt":"2024-12-30T15:39:16","slug":"fotografia","status":"publish","type":"page","link":"https:\/\/martinopietropoli.com\/en\/fotografia","title":{"rendered":"Photography"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"29866\" class=\"elementor elementor-29866\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e5c1769 elementor-section-content-middle elementor-section-full_width elementor-section-height-default elementor-section-height-default neuron-fixed-no\" data-id=\"e5c1769\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fbf29ac\" data-id=\"fbf29ac\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1cfbeb7 elementor-section-boxed elementor-section-height-default elementor-section-height-default neuron-fixed-no\" data-id=\"1cfbeb7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-081250b\" data-id=\"081250b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-13ee8e0\" data-id=\"13ee8e0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-43d384b elementor-widget elementor-widget-heading\" data-id=\"43d384b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Photography<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-64b3d66 elementor-widget elementor-widget-heading\" data-id=\"64b3d66\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Fotografo da decenni. Architettura, reportage, luoghi, spesso e soprattutto quelli che non si degna mai di uno sguardo perch\u00e9 non sono belli. Qualcuno mi ha detto che so cogliere il margine e il dettaglio che sfugge normalmente. Mi muovo ai margini, ecco.\u200b<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8c57511 elementor-section-full_width elementor-section-height-default elementor-section-height-default neuron-fixed-no\" data-id=\"8c57511\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7896693\" data-id=\"7896693\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2958f24 elementor-widget elementor-widget-neuron-posts\" data-id=\"2958f24\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"neuron-posts.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"l-posts-wrapper l-filters-holder l-posts-wrapper--meta-outside h-overflow-hidden l-portfolio-wrapper\" data-posts=\"2958f24\">\n\t\t\t<div class=\"m-filters\">\n    <ul id=\"filters\">\n                    <li class=\"active\" data-filter=\"*\"><a>Show All<\/a><\/li>\n                <li data-filter=\".architecture\"><a>Architecture<\/a><\/li><li data-filter=\".city\"><a>City<\/a><\/li><li data-filter=\".nature\"><a>Nature<\/a><\/li><li data-filter=\".travel\"><a>Travel<\/a><\/li>    <\/ul>\n<\/div>\t\t\t\t\t\t<div class=\"l-portfolio-wrapper__items-holder l-portfolio-wrapper__items-holder--meta-outside h-overflow-hidden\">\n\t\t\t\t    <div class=\"row masonry\" data-masonry-id=\"f3d6e65b6db25d2f0e1593e1abecf84c\">\n                                <div class=\"selector col-lg-6 architecture city photography travel post-31518 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-architecture portfolio_category-city portfolio_category-photography portfolio_category-travel\" data-id=\"31518\" data-columns=\"2-columns\">\n                <div class=\"o-post o-portfolio-item wow h-fadeInNeuron\" >\n                        <div class=\"o-neuron-hover\">\n        <div class=\"o-neuron-hover-holder\">\n            <div class=\"o-neuron-hover-holder__header\">\n                                    <a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/sternbrauerei-salzburg\" class=\"o-neuron-hover-holder__header__media\">\n                                                    <div class=\"h-calculated-image\" style=\"padding-bottom: 100.000000% !important;\">\n                                <img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/a2208c_c28e72dbaf89448b9a02dff9d46c38ec-mv2_d_2048_1356_s_2-300x300.jpg\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/a2208c_c28e72dbaf89448b9a02dff9d46c38ec-mv2_d_2048_1356_s_2-300x300.jpg 300w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/a2208c_c28e72dbaf89448b9a02dff9d46c38ec-mv2_d_2048_1356_s_2-150x150.jpg 150w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/a2208c_c28e72dbaf89448b9a02dff9d46c38ec-mv2_d_2048_1356_s_2-500x500.jpg 500w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/a2208c_c28e72dbaf89448b9a02dff9d46c38ec-mv2_d_2048_1356_s_2-1000x1000.jpg 1000w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/a2208c_c28e72dbaf89448b9a02dff9d46c38ec-mv2_d_2048_1356_s_2-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>                            <\/div>\n                                            <\/a>\n                                            <\/div>\n                    <\/div>\n    <\/div>\n<div class=\"o-portfolio-item__content o-neuron-post__content\">\n            <h5 class=\"o-portfolio-item__title o-neuron-post__title\"><a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/sternbrauerei-salzburg\">Sternbrauerei Salzburg<\/a><\/h5>\n        <\/div>                <\/div>\n            <\/div>\n                                <div class=\"selector col-lg-6 architecture photography travel post-31570 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-architecture portfolio_category-photography portfolio_category-travel\" data-id=\"31570\" data-columns=\"2-columns\">\n                <div class=\"o-post o-portfolio-item wow h-fadeInNeuron\" >\n                        <div class=\"o-neuron-hover\">\n        <div class=\"o-neuron-hover-holder\">\n            <div class=\"o-neuron-hover-holder__header\">\n                                    <a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/ottolenghi-house\" class=\"o-neuron-hover-holder__header__media\">\n                                                    <div class=\"h-calculated-image\" style=\"padding-bottom: 100.000000% !important;\">\n                                <img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/a2208c_644d62f880244565a28e4681d44079ef-mv2_d_2000_1600_s_2-300x300.jpeg\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/a2208c_644d62f880244565a28e4681d44079ef-mv2_d_2000_1600_s_2-300x300.jpeg 300w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/a2208c_644d62f880244565a28e4681d44079ef-mv2_d_2000_1600_s_2-150x150.jpeg 150w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/a2208c_644d62f880244565a28e4681d44079ef-mv2_d_2000_1600_s_2-500x500.jpeg 500w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/a2208c_644d62f880244565a28e4681d44079ef-mv2_d_2000_1600_s_2-1000x1000.jpeg 1000w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/a2208c_644d62f880244565a28e4681d44079ef-mv2_d_2000_1600_s_2-100x100.jpeg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>                            <\/div>\n                                            <\/a>\n                                            <\/div>\n                    <\/div>\n    <\/div>\n<div class=\"o-portfolio-item__content o-neuron-post__content\">\n            <h5 class=\"o-portfolio-item__title o-neuron-post__title\"><a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/ottolenghi-house\">Ottolenghi House<\/a><\/h5>\n        <\/div>                <\/div>\n            <\/div>\n                                <div class=\"selector col-lg-6 architecture photography post-40626 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-architecture portfolio_category-photography\" data-id=\"40626\" data-columns=\"2-columns\">\n                <div class=\"o-post o-portfolio-item wow h-fadeInNeuron\" >\n                        <div class=\"o-neuron-hover\">\n        <div class=\"o-neuron-hover-holder\">\n            <div class=\"o-neuron-hover-holder__header\">\n                                    <a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/fondazione-luigi-rovati\" class=\"o-neuron-hover-holder__header__media\">\n                                                    <div class=\"h-calculated-image\" style=\"padding-bottom: 66.650391% !important;\">\n                                <img decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2023\/10\/DSCF0225.jpg\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2023\/10\/DSCF0225.jpg 2048w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2023\/10\/DSCF0225-300x200.jpg 300w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2023\/10\/DSCF0225-1024x683.jpg 1024w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2023\/10\/DSCF0225-768x512.jpg 768w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2023\/10\/DSCF0225-1536x1024.jpg 1536w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2023\/10\/DSCF0225-18x12.jpg 18w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/>                            <\/div>\n                                            <\/a>\n                                            <\/div>\n                    <\/div>\n    <\/div>\n<div class=\"o-portfolio-item__content o-neuron-post__content\">\n            <h5 class=\"o-portfolio-item__title o-neuron-post__title\"><a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/fondazione-luigi-rovati\">Luigi Rovati Foundation<\/a><\/h5>\n        <\/div>                <\/div>\n            <\/div>\n                                <div class=\"selector col-lg-6 architecture photography post-37482 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-architecture portfolio_category-photography\" data-id=\"37482\" data-columns=\"2-columns\">\n                <div class=\"o-post o-portfolio-item wow h-fadeInNeuron\" >\n                        <div class=\"o-neuron-hover\">\n        <div class=\"o-neuron-hover-holder\">\n            <div class=\"o-neuron-hover-holder__header\">\n                                    <a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/h-farm-roncade-studio-zanon-associati\" class=\"o-neuron-hover-holder__header__media\">\n                                                    <div class=\"h-calculated-image\" style=\"padding-bottom: 66.637744% !important;\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"2305\" height=\"1536\" src=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2016\/07\/IMG_0005.jpg\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2016\/07\/IMG_0005.jpg 2305w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2016\/07\/IMG_0005-300x200.jpg 300w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2016\/07\/IMG_0005-1024x682.jpg 1024w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2016\/07\/IMG_0005-768x512.jpg 768w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2016\/07\/IMG_0005-1536x1024.jpg 1536w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2016\/07\/IMG_0005-2048x1365.jpg 2048w\" sizes=\"(max-width: 2305px) 100vw, 2305px\" \/>                            <\/div>\n                                            <\/a>\n                                            <\/div>\n                    <\/div>\n    <\/div>\n<div class=\"o-portfolio-item__content o-neuron-post__content\">\n            <h5 class=\"o-portfolio-item__title o-neuron-post__title\"><a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/h-farm-roncade-studio-zanon-associati\">H-Farm<\/a><\/h5>\n        <\/div>                <\/div>\n            <\/div>\n                                <div class=\"selector col-lg-6 city photography travel post-33617 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-city portfolio_category-photography portfolio_category-travel\" data-id=\"33617\" data-columns=\"2-columns\">\n                <div class=\"o-post o-portfolio-item wow h-fadeInNeuron\" >\n                        <div class=\"o-neuron-hover\">\n        <div class=\"o-neuron-hover-holder\">\n            <div class=\"o-neuron-hover-holder__header\">\n                                    <a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/budapest\" class=\"o-neuron-hover-holder__header__media\">\n                                                    <div class=\"h-calculated-image\" style=\"padding-bottom: 66.679688% !important;\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2020\/01\/DSCF1498-scaled.jpg\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2020\/01\/DSCF1498-scaled.jpg 2560w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2020\/01\/DSCF1498-300x200.jpg 300w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2020\/01\/DSCF1498-1024x683.jpg 1024w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2020\/01\/DSCF1498-768x512.jpg 768w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2020\/01\/DSCF1498-1536x1024.jpg 1536w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2020\/01\/DSCF1498-2048x1365.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>                            <\/div>\n                                            <\/a>\n                                            <\/div>\n                    <\/div>\n    <\/div>\n<div class=\"o-portfolio-item__content o-neuron-post__content\">\n            <h5 class=\"o-portfolio-item__title o-neuron-post__title\"><a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/budapest\">Budapest<\/a><\/h5>\n        <\/div>                <\/div>\n            <\/div>\n                                <div class=\"selector col-lg-6 photography travel post-30675 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-photography portfolio_category-travel\" data-id=\"30675\" data-columns=\"2-columns\">\n                <div class=\"o-post o-portfolio-item wow h-fadeInNeuron\" >\n                        <div class=\"o-neuron-hover\">\n        <div class=\"o-neuron-hover-holder\">\n            <div class=\"o-neuron-hover-holder__header\">\n                                    <a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/randomothos\" class=\"o-neuron-hover-holder__header__media\">\n                                                    <div class=\"h-calculated-image\" style=\"padding-bottom: 66.562500% !important;\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1704\" src=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/IMG_0515-scaled.jpg\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/IMG_0515-scaled.jpg 2560w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/IMG_0515-300x200.jpg 300w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/IMG_0515-1024x682.jpg 1024w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/IMG_0515-768x511.jpg 768w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/IMG_0515-1536x1022.jpg 1536w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/IMG_0515-2048x1363.jpg 2048w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/IMG_0515-16x12.jpg 16w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>                            <\/div>\n                                            <\/a>\n                                            <\/div>\n                    <\/div>\n    <\/div>\n<div class=\"o-portfolio-item__content o-neuron-post__content\">\n            <h5 class=\"o-portfolio-item__title o-neuron-post__title\"><a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/randomothos\">Randomothos<\/a><\/h5>\n        <\/div>                <\/div>\n            <\/div>\n                                <div class=\"selector col-lg-6 architecture photography post-38598 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-architecture portfolio_category-photography\" data-id=\"38598\" data-columns=\"2-columns\">\n                <div class=\"o-post o-portfolio-item wow h-fadeInNeuron\" >\n                        <div class=\"o-neuron-hover\">\n        <div class=\"o-neuron-hover-holder\">\n            <div class=\"o-neuron-hover-holder__header\">\n                                    <a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/little-island-new-york-thomas-heatherwick\" class=\"o-neuron-hover-holder__header__media\">\n                                                    <div class=\"h-calculated-image\" style=\"padding-bottom: 66.679688% !important;\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2022\/09\/0D5CB857-9FE0-46FB-BF32-C191BA38D02A-scaled.jpeg\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2022\/09\/0D5CB857-9FE0-46FB-BF32-C191BA38D02A-scaled.jpeg 2560w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2022\/09\/0D5CB857-9FE0-46FB-BF32-C191BA38D02A-300x200.jpeg 300w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2022\/09\/0D5CB857-9FE0-46FB-BF32-C191BA38D02A-1024x683.jpeg 1024w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2022\/09\/0D5CB857-9FE0-46FB-BF32-C191BA38D02A-768x512.jpeg 768w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2022\/09\/0D5CB857-9FE0-46FB-BF32-C191BA38D02A-1536x1024.jpeg 1536w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2022\/09\/0D5CB857-9FE0-46FB-BF32-C191BA38D02A-2048x1365.jpeg 2048w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2022\/09\/0D5CB857-9FE0-46FB-BF32-C191BA38D02A-18x12.jpeg 18w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>                            <\/div>\n                                            <\/a>\n                                            <\/div>\n                    <\/div>\n    <\/div>\n<div class=\"o-portfolio-item__content o-neuron-post__content\">\n            <h5 class=\"o-portfolio-item__title o-neuron-post__title\"><a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/little-island-new-york-thomas-heatherwick\">Little Island, New York<\/a><\/h5>\n        <\/div>                <\/div>\n            <\/div>\n                                <div class=\"selector col-lg-6 photography travel post-33208 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-photography portfolio_category-travel\" data-id=\"33208\" data-columns=\"2-columns\">\n                <div class=\"o-post o-portfolio-item wow h-fadeInNeuron\" >\n                        <div class=\"o-neuron-hover\">\n        <div class=\"o-neuron-hover-holder\">\n            <div class=\"o-neuron-hover-holder__header\">\n                                    <a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/croazia\" class=\"o-neuron-hover-holder__header__media\">\n                                                    <div class=\"h-calculated-image\" style=\"padding-bottom: 67.826618% !important;\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"1638\" height=\"1111\" src=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/12\/a2208c_4a256a2cc7f54d5b974dc207a2b26992_mv2_d_1638_2048_s_2-2.jpg\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/12\/a2208c_4a256a2cc7f54d5b974dc207a2b26992_mv2_d_1638_2048_s_2-2.jpg 1638w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/12\/a2208c_4a256a2cc7f54d5b974dc207a2b26992_mv2_d_1638_2048_s_2-2-300x203.jpg 300w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/12\/a2208c_4a256a2cc7f54d5b974dc207a2b26992_mv2_d_1638_2048_s_2-2-1024x695.jpg 1024w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/12\/a2208c_4a256a2cc7f54d5b974dc207a2b26992_mv2_d_1638_2048_s_2-2-768x521.jpg 768w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/12\/a2208c_4a256a2cc7f54d5b974dc207a2b26992_mv2_d_1638_2048_s_2-2-1536x1042.jpg 1536w\" sizes=\"(max-width: 1638px) 100vw, 1638px\" \/>                            <\/div>\n                                            <\/a>\n                                            <\/div>\n                    <\/div>\n    <\/div>\n<div class=\"o-portfolio-item__content o-neuron-post__content\">\n            <h5 class=\"o-portfolio-item__title o-neuron-post__title\"><a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/croazia\">Croatia<\/a><\/h5>\n        <\/div>                <\/div>\n            <\/div>\n                                <div class=\"selector col-lg-6 architecture city photography travel post-31342 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-architecture portfolio_category-city portfolio_category-photography portfolio_category-travel\" data-id=\"31342\" data-columns=\"2-columns\">\n                <div class=\"o-post o-portfolio-item wow h-fadeInNeuron\" >\n                        <div class=\"o-neuron-hover\">\n        <div class=\"o-neuron-hover-holder\">\n            <div class=\"o-neuron-hover-holder__header\">\n                                    <a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/berlin-jewish-museum\" class=\"o-neuron-hover-holder__header__media\">\n                                                    <div class=\"h-calculated-image\" style=\"padding-bottom: 100.000000% !important;\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/a2208c_7a20a1a04f0841fb8d1832b729c00a98-mv2_d_2048_1356_s_2-300x300.jpg\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/a2208c_7a20a1a04f0841fb8d1832b729c00a98-mv2_d_2048_1356_s_2-300x300.jpg 300w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/a2208c_7a20a1a04f0841fb8d1832b729c00a98-mv2_d_2048_1356_s_2-150x150.jpg 150w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/a2208c_7a20a1a04f0841fb8d1832b729c00a98-mv2_d_2048_1356_s_2-500x500.jpg 500w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/a2208c_7a20a1a04f0841fb8d1832b729c00a98-mv2_d_2048_1356_s_2-1000x1000.jpg 1000w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/a2208c_7a20a1a04f0841fb8d1832b729c00a98-mv2_d_2048_1356_s_2-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>                            <\/div>\n                                            <\/a>\n                                            <\/div>\n                    <\/div>\n    <\/div>\n<div class=\"o-portfolio-item__content o-neuron-post__content\">\n            <h5 class=\"o-portfolio-item__title o-neuron-post__title\"><a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/berlin-jewish-museum\">Berlin Jewish Museum<\/a><\/h5>\n        <\/div>                <\/div>\n            <\/div>\n                                <div class=\"selector col-lg-6 architecture featured_ph travel post-34062 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-architecture portfolio_category-featured_ph portfolio_category-travel\" data-id=\"34062\" data-columns=\"2-columns\">\n                <div class=\"o-post o-portfolio-item wow h-fadeInNeuron\" >\n                        <div class=\"o-neuron-hover\">\n        <div class=\"o-neuron-hover-holder\">\n            <div class=\"o-neuron-hover-holder__header\">\n                                    <a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/h-farm-2\" class=\"o-neuron-hover-holder__header__media\">\n                                                    <div class=\"h-calculated-image\" style=\"padding-bottom: 66.637744% !important;\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"2305\" height=\"1536\" src=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2016\/07\/IMG_0005.jpg\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2016\/07\/IMG_0005.jpg 2305w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2016\/07\/IMG_0005-300x200.jpg 300w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2016\/07\/IMG_0005-1024x682.jpg 1024w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2016\/07\/IMG_0005-768x512.jpg 768w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2016\/07\/IMG_0005-1536x1024.jpg 1536w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2016\/07\/IMG_0005-2048x1365.jpg 2048w\" sizes=\"(max-width: 2305px) 100vw, 2305px\" \/>                            <\/div>\n                                            <\/a>\n                                            <\/div>\n                    <\/div>\n    <\/div>\n<div class=\"o-portfolio-item__content o-neuron-post__content\">\n            <h5 class=\"o-portfolio-item__title o-neuron-post__title\"><a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/h-farm-2\">H-Farm<\/a><\/h5>\n        <\/div>                <\/div>\n            <\/div>\n                                <div class=\"selector col-lg-6 architecture photography post-38265 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-architecture portfolio_category-photography\" data-id=\"38265\" data-columns=\"2-columns\">\n                <div class=\"o-post o-portfolio-item wow h-fadeInNeuron\" >\n                        <div class=\"o-neuron-hover\">\n        <div class=\"o-neuron-hover-holder\">\n            <div class=\"o-neuron-hover-holder__header\">\n                                    <a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/lo-studio-casa-di-formafantasma\" class=\"o-neuron-hover-holder__header__media\">\n                                                    <div class=\"h-calculated-image\" style=\"padding-bottom: 66.650000% !important;\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"1333\" src=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2022\/08\/IMG_9535.jpg\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2022\/08\/IMG_9535.jpg 2000w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2022\/08\/IMG_9535-300x200.jpg 300w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2022\/08\/IMG_9535-1024x682.jpg 1024w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2022\/08\/IMG_9535-768x512.jpg 768w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2022\/08\/IMG_9535-1536x1024.jpg 1536w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2022\/08\/IMG_9535-18x12.jpg 18w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/>                            <\/div>\n                                            <\/a>\n                                            <\/div>\n                    <\/div>\n    <\/div>\n<div class=\"o-portfolio-item__content o-neuron-post__content\">\n            <h5 class=\"o-portfolio-item__title o-neuron-post__title\"><a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/lo-studio-casa-di-formafantasma\">Lo studio-casa di Formafantasma<\/a><\/h5>\n        <\/div>                <\/div>\n            <\/div>\n                                <div class=\"selector col-lg-6 photography travel post-32685 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-photography portfolio_category-travel\" data-id=\"32685\" data-columns=\"2-columns\">\n                <div class=\"o-post o-portfolio-item wow h-fadeInNeuron\" >\n                        <div class=\"o-neuron-hover\">\n        <div class=\"o-neuron-hover-holder\">\n            <div class=\"o-neuron-hover-holder__header\">\n                                    <a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/marche\" class=\"o-neuron-hover-holder__header__media\">\n                                                    <div class=\"h-calculated-image\" style=\"padding-bottom: 62.477120% !important;\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"1639\" height=\"1024\" src=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/11\/a2208c_fe20ff69e5d14b64aadb7ae8ff8cb8bd_mv2.jpeg\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/11\/a2208c_fe20ff69e5d14b64aadb7ae8ff8cb8bd_mv2.jpeg 1639w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/11\/a2208c_fe20ff69e5d14b64aadb7ae8ff8cb8bd_mv2-300x187.jpeg 300w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/11\/a2208c_fe20ff69e5d14b64aadb7ae8ff8cb8bd_mv2-1024x640.jpeg 1024w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/11\/a2208c_fe20ff69e5d14b64aadb7ae8ff8cb8bd_mv2-768x480.jpeg 768w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/11\/a2208c_fe20ff69e5d14b64aadb7ae8ff8cb8bd_mv2-1536x960.jpeg 1536w\" sizes=\"(max-width: 1639px) 100vw, 1639px\" \/>                            <\/div>\n                                            <\/a>\n                                            <\/div>\n                    <\/div>\n    <\/div>\n<div class=\"o-portfolio-item__content o-neuron-post__content\">\n            <h5 class=\"o-portfolio-item__title o-neuron-post__title\"><a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/marche\">Marche<\/a><\/h5>\n        <\/div>                <\/div>\n            <\/div>\n                                <div class=\"selector col-lg-6 photography travel post-32712 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-photography portfolio_category-travel\" data-id=\"32712\" data-columns=\"2-columns\">\n                <div class=\"o-post o-portfolio-item wow h-fadeInNeuron\" >\n                        <div class=\"o-neuron-hover\">\n        <div class=\"o-neuron-hover-holder\">\n            <div class=\"o-neuron-hover-holder__header\">\n                                    <a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/vietnam\" class=\"o-neuron-hover-holder__header__media\">\n                                                    <div class=\"h-calculated-image\" style=\"padding-bottom: 66.493506% !important;\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"2310\" height=\"1536\" src=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2011\/11\/a2208c_32af8d8a0c594484874faca89f472254_mv2_d_2310_1536_s_2.jpg\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2011\/11\/a2208c_32af8d8a0c594484874faca89f472254_mv2_d_2310_1536_s_2.jpg 2310w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2011\/11\/a2208c_32af8d8a0c594484874faca89f472254_mv2_d_2310_1536_s_2-300x199.jpg 300w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2011\/11\/a2208c_32af8d8a0c594484874faca89f472254_mv2_d_2310_1536_s_2-1024x681.jpg 1024w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2011\/11\/a2208c_32af8d8a0c594484874faca89f472254_mv2_d_2310_1536_s_2-768x511.jpg 768w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2011\/11\/a2208c_32af8d8a0c594484874faca89f472254_mv2_d_2310_1536_s_2-1536x1021.jpg 1536w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2011\/11\/a2208c_32af8d8a0c594484874faca89f472254_mv2_d_2310_1536_s_2-2048x1362.jpg 2048w\" sizes=\"(max-width: 2310px) 100vw, 2310px\" \/>                            <\/div>\n                                            <\/a>\n                                            <\/div>\n                    <\/div>\n    <\/div>\n<div class=\"o-portfolio-item__content o-neuron-post__content\">\n            <h5 class=\"o-portfolio-item__title o-neuron-post__title\"><a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/vietnam\">Vietnam<\/a><\/h5>\n        <\/div>                <\/div>\n            <\/div>\n                                <div class=\"selector col-lg-6 city featured_ph photography travel post-33860 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-city portfolio_category-featured_ph portfolio_category-photography portfolio_category-travel\" data-id=\"33860\" data-columns=\"2-columns\">\n                <div class=\"o-post o-portfolio-item wow h-fadeInNeuron\" >\n                        <div class=\"o-neuron-hover\">\n        <div class=\"o-neuron-hover-holder\">\n            <div class=\"o-neuron-hover-holder__header\">\n                                    <a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/ischia\" class=\"o-neuron-hover-holder__header__media\">\n                                                    <div class=\"h-calculated-image\" style=\"padding-bottom: 66.785460% !important;\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"1403\" height=\"937\" src=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2020\/04\/3908E8C5-2B57-432B-9A71-4EEBF2EDD089.jpg\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2020\/04\/3908E8C5-2B57-432B-9A71-4EEBF2EDD089.jpg 1403w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2020\/04\/3908E8C5-2B57-432B-9A71-4EEBF2EDD089-300x200.jpg 300w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2020\/04\/3908E8C5-2B57-432B-9A71-4EEBF2EDD089-1024x684.jpg 1024w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2020\/04\/3908E8C5-2B57-432B-9A71-4EEBF2EDD089-768x513.jpg 768w\" sizes=\"(max-width: 1403px) 100vw, 1403px\" \/>                            <\/div>\n                                            <\/a>\n                                            <\/div>\n                    <\/div>\n    <\/div>\n<div class=\"o-portfolio-item__content o-neuron-post__content\">\n            <h5 class=\"o-portfolio-item__title o-neuron-post__title\"><a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/ischia\">La nostalgia del futuro (Ischia\/Capri\/Procida)<\/a><\/h5>\n        <\/div>                <\/div>\n            <\/div>\n                                <div class=\"selector col-lg-6 architecture photography post-41854 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-architecture portfolio_category-photography\" data-id=\"41854\" data-columns=\"2-columns\">\n                <div class=\"o-post o-portfolio-item wow h-fadeInNeuron\" >\n                        <div class=\"o-neuron-hover\">\n        <div class=\"o-neuron-hover-holder\">\n            <div class=\"o-neuron-hover-holder__header\">\n                                    <a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/les-tres-xemeneies\" class=\"o-neuron-hover-holder__header__media\">\n                                                    <div class=\"h-calculated-image\" style=\"padding-bottom: 66.407982% !important;\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"1804\" height=\"1198\" src=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2026\/07\/Screenshot-2026-07-12-at-14.15.53.png\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"Les Tres Xemeneies - Barcelona\" srcset=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2026\/07\/Screenshot-2026-07-12-at-14.15.53.png 1804w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2026\/07\/Screenshot-2026-07-12-at-14.15.53-300x199.png 300w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2026\/07\/Screenshot-2026-07-12-at-14.15.53-1024x680.png 1024w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2026\/07\/Screenshot-2026-07-12-at-14.15.53-768x510.png 768w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2026\/07\/Screenshot-2026-07-12-at-14.15.53-1536x1020.png 1536w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2026\/07\/Screenshot-2026-07-12-at-14.15.53-18x12.png 18w\" sizes=\"(max-width: 1804px) 100vw, 1804px\" \/>                            <\/div>\n                                            <\/a>\n                                            <\/div>\n                    <\/div>\n    <\/div>\n<div class=\"o-portfolio-item__content o-neuron-post__content\">\n            <h5 class=\"o-portfolio-item__title o-neuron-post__title\"><a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/les-tres-xemeneies\">Les Tres Xemeneies<\/a><\/h5>\n        <\/div>                <\/div>\n            <\/div>\n                                <div class=\"selector col-lg-6 nature photography travel post-31090 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-nature portfolio_category-photography portfolio_category-travel\" data-id=\"31090\" data-columns=\"2-columns\">\n                <div class=\"o-post o-portfolio-item wow h-fadeInNeuron\" >\n                        <div class=\"o-neuron-hover\">\n        <div class=\"o-neuron-hover-holder\">\n            <div class=\"o-neuron-hover-holder__header\">\n                                    <a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/jordan\" class=\"o-neuron-hover-holder__header__media\">\n                                                    <div class=\"h-calculated-image\" style=\"padding-bottom: 100.000000% !important;\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/JOR_01-300x300.jpg\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/JOR_01-300x300.jpg 300w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/JOR_01-150x150.jpg 150w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/JOR_01-500x500.jpg 500w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/JOR_01-1000x1000.jpg 1000w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/JOR_01-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>                            <\/div>\n                                            <\/a>\n                                            <\/div>\n                    <\/div>\n    <\/div>\n<div class=\"o-portfolio-item__content o-neuron-post__content\">\n            <h5 class=\"o-portfolio-item__title o-neuron-post__title\"><a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/jordan\">Jordan<\/a><\/h5>\n        <\/div>                <\/div>\n            <\/div>\n                                <div class=\"selector col-lg-6 architecture post-31536 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-architecture\" data-id=\"31536\" data-columns=\"2-columns\">\n                <div class=\"o-post o-portfolio-item wow h-fadeInNeuron\" >\n                        <div class=\"o-neuron-hover\">\n        <div class=\"o-neuron-hover-holder\">\n            <div class=\"o-neuron-hover-holder__header\">\n                                    <a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/brion-cemetery\" class=\"o-neuron-hover-holder__header__media\">\n                                                    <div class=\"h-calculated-image\" style=\"padding-bottom: 100.000000% !important;\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/a2208c_676e1faea26041d59c86dede29938f6b-mv2_d_2216_2200_s_2-300x300.jpg\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/a2208c_676e1faea26041d59c86dede29938f6b-mv2_d_2216_2200_s_2-300x300.jpg 300w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/a2208c_676e1faea26041d59c86dede29938f6b-mv2_d_2216_2200_s_2-150x150.jpg 150w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/a2208c_676e1faea26041d59c86dede29938f6b-mv2_d_2216_2200_s_2-500x500.jpg 500w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/a2208c_676e1faea26041d59c86dede29938f6b-mv2_d_2216_2200_s_2-1000x1000.jpg 1000w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/a2208c_676e1faea26041d59c86dede29938f6b-mv2_d_2216_2200_s_2-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>                            <\/div>\n                                            <\/a>\n                                            <\/div>\n                    <\/div>\n    <\/div>\n<div class=\"o-portfolio-item__content o-neuron-post__content\">\n            <h5 class=\"o-portfolio-item__title o-neuron-post__title\"><a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/brion-cemetery\">Brion Memorial<\/a><\/h5>\n        <\/div>                <\/div>\n            <\/div>\n                                <div class=\"selector col-lg-6 nature photography travel post-31119 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-nature portfolio_category-photography portfolio_category-travel\" data-id=\"31119\" data-columns=\"2-columns\">\n                <div class=\"o-post o-portfolio-item wow h-fadeInNeuron\" >\n                        <div class=\"o-neuron-hover\">\n        <div class=\"o-neuron-hover-holder\">\n            <div class=\"o-neuron-hover-holder__header\">\n                                    <a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/scotland\" class=\"o-neuron-hover-holder__header__media\">\n                                                    <div class=\"h-calculated-image\" style=\"padding-bottom: 100.000000% !important;\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/a2208c_1e3e8edbd06646c89e418267902aa810_mv2_d_1638_2048_s_2-300x300.jpg\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/a2208c_1e3e8edbd06646c89e418267902aa810_mv2_d_1638_2048_s_2-300x300.jpg 300w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/a2208c_1e3e8edbd06646c89e418267902aa810_mv2_d_1638_2048_s_2-150x150.jpg 150w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/a2208c_1e3e8edbd06646c89e418267902aa810_mv2_d_1638_2048_s_2-500x500.jpg 500w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/a2208c_1e3e8edbd06646c89e418267902aa810_mv2_d_1638_2048_s_2-1000x1000.jpg 1000w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/a2208c_1e3e8edbd06646c89e418267902aa810_mv2_d_1638_2048_s_2-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>                            <\/div>\n                                            <\/a>\n                                            <\/div>\n                    <\/div>\n    <\/div>\n<div class=\"o-portfolio-item__content o-neuron-post__content\">\n            <h5 class=\"o-portfolio-item__title o-neuron-post__title\"><a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/scotland\">Scotland<\/a><\/h5>\n        <\/div>                <\/div>\n            <\/div>\n                                <div class=\"selector col-lg-6 architecture photography post-38119 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-architecture portfolio_category-photography\" data-id=\"38119\" data-columns=\"2-columns\">\n                <div class=\"o-post o-portfolio-item wow h-fadeInNeuron\" >\n                        <div class=\"o-neuron-hover\">\n        <div class=\"o-neuron-hover-holder\">\n            <div class=\"o-neuron-hover-holder__header\">\n                                    <a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/aldo-rossi-cimitero-di-san-cataldo-modena\" class=\"o-neuron-hover-holder__header__media\">\n                                                    <div class=\"h-calculated-image\" style=\"padding-bottom: 66.679688% !important;\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2022\/08\/B6852128-D431-4D38-A880-2896A6DC6250-scaled.jpeg\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2022\/08\/B6852128-D431-4D38-A880-2896A6DC6250-scaled.jpeg 2560w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2022\/08\/B6852128-D431-4D38-A880-2896A6DC6250-300x200.jpeg 300w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2022\/08\/B6852128-D431-4D38-A880-2896A6DC6250-1024x683.jpeg 1024w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2022\/08\/B6852128-D431-4D38-A880-2896A6DC6250-768x512.jpeg 768w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2022\/08\/B6852128-D431-4D38-A880-2896A6DC6250-1536x1024.jpeg 1536w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2022\/08\/B6852128-D431-4D38-A880-2896A6DC6250-2048x1365.jpeg 2048w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2022\/08\/B6852128-D431-4D38-A880-2896A6DC6250-18x12.jpeg 18w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>                            <\/div>\n                                            <\/a>\n                                            <\/div>\n                    <\/div>\n    <\/div>\n<div class=\"o-portfolio-item__content o-neuron-post__content\">\n            <h5 class=\"o-portfolio-item__title o-neuron-post__title\"><a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/aldo-rossi-cimitero-di-san-cataldo-modena\">Aldo Rossi, Cimitero di San Cataldo, Modena<\/a><\/h5>\n        <\/div>                <\/div>\n            <\/div>\n                                <div class=\"selector col-lg-6 architecture photography post-40953 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-architecture portfolio_category-photography\" data-id=\"40953\" data-columns=\"2-columns\">\n                <div class=\"o-post o-portfolio-item wow h-fadeInNeuron\" >\n                        <div class=\"o-neuron-hover\">\n        <div class=\"o-neuron-hover-holder\">\n            <div class=\"o-neuron-hover-holder__header\">\n                                    <a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/palazzo-delle-poste-napoli\" class=\"o-neuron-hover-holder__header__media\">\n                                                    <div class=\"h-calculated-image\" style=\"padding-bottom: 72.304688% !important;\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1851\" src=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2024\/08\/072C6DE3-C2B7-4369-BFFF-1B8E486E4669-scaled.jpg\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2024\/08\/072C6DE3-C2B7-4369-BFFF-1B8E486E4669-scaled.jpg 2560w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2024\/08\/072C6DE3-C2B7-4369-BFFF-1B8E486E4669-300x217.jpg 300w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2024\/08\/072C6DE3-C2B7-4369-BFFF-1B8E486E4669-1024x740.jpg 1024w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2024\/08\/072C6DE3-C2B7-4369-BFFF-1B8E486E4669-768x555.jpg 768w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2024\/08\/072C6DE3-C2B7-4369-BFFF-1B8E486E4669-1536x1110.jpg 1536w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2024\/08\/072C6DE3-C2B7-4369-BFFF-1B8E486E4669-2048x1480.jpg 2048w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2024\/08\/072C6DE3-C2B7-4369-BFFF-1B8E486E4669-18x12.jpg 18w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>                            <\/div>\n                                            <\/a>\n                                            <\/div>\n                    <\/div>\n    <\/div>\n<div class=\"o-portfolio-item__content o-neuron-post__content\">\n            <h5 class=\"o-portfolio-item__title o-neuron-post__title\"><a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/palazzo-delle-poste-napoli\">Palazzo delle Poste, Napoli<\/a><\/h5>\n        <\/div>                <\/div>\n            <\/div>\n                                <div class=\"selector col-lg-6 architecture featured_ph photography travel post-34794 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-architecture portfolio_category-featured_ph portfolio_category-photography portfolio_category-travel\" data-id=\"34794\" data-columns=\"2-columns\">\n                <div class=\"o-post o-portfolio-item wow h-fadeInNeuron\" >\n                        <div class=\"o-neuron-hover\">\n        <div class=\"o-neuron-hover-holder\">\n            <div class=\"o-neuron-hover-holder__header\">\n                                    <a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/casa-balboni-carlo-scarpa-venezia-venice\" class=\"o-neuron-hover-holder__header__media\">\n                                                    <div class=\"h-calculated-image\" style=\"padding-bottom: 133.398438% !important;\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"1536\" height=\"2049\" src=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2021\/03\/14B73AE0-DB6D-4B54-B6AC-ACEE55831FD3.jpg\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2021\/03\/14B73AE0-DB6D-4B54-B6AC-ACEE55831FD3.jpg 1536w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2021\/03\/14B73AE0-DB6D-4B54-B6AC-ACEE55831FD3-225x300.jpg 225w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2021\/03\/14B73AE0-DB6D-4B54-B6AC-ACEE55831FD3-768x1025.jpg 768w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2021\/03\/14B73AE0-DB6D-4B54-B6AC-ACEE55831FD3-1151x1536.jpg 1151w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2021\/03\/14B73AE0-DB6D-4B54-B6AC-ACEE55831FD3-9x12.jpg 9w\" sizes=\"(max-width: 1536px) 100vw, 1536px\" \/>                            <\/div>\n                                            <\/a>\n                                            <\/div>\n                    <\/div>\n    <\/div>\n<div class=\"o-portfolio-item__content o-neuron-post__content\">\n            <h5 class=\"o-portfolio-item__title o-neuron-post__title\"><a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/casa-balboni-carlo-scarpa-venezia-venice\">Casa Balboni<\/a><\/h5>\n        <\/div>                <\/div>\n            <\/div>\n                                <div class=\"selector col-lg-6 architecture photography post-40651 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-architecture portfolio_category-photography\" data-id=\"40651\" data-columns=\"2-columns\">\n                <div class=\"o-post o-portfolio-item wow h-fadeInNeuron\" >\n                        <div class=\"o-neuron-hover\">\n        <div class=\"o-neuron-hover-holder\">\n            <div class=\"o-neuron-hover-holder__header\">\n                                    <a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/kmska-koninklijk-museum-voor-schone-kunsten-antwerp\" class=\"o-neuron-hover-holder__header__media\">\n                                                    <div class=\"h-calculated-image\" style=\"padding-bottom: 150.036630% !important;\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"1365\" height=\"2048\" src=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2023\/10\/L1320986.jpg\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2023\/10\/L1320986.jpg 1365w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2023\/10\/L1320986-200x300.jpg 200w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2023\/10\/L1320986-683x1024.jpg 683w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2023\/10\/L1320986-768x1152.jpg 768w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2023\/10\/L1320986-1024x1536.jpg 1024w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2023\/10\/L1320986-8x12.jpg 8w\" sizes=\"(max-width: 1365px) 100vw, 1365px\" \/>                            <\/div>\n                                            <\/a>\n                                            <\/div>\n                    <\/div>\n    <\/div>\n<div class=\"o-portfolio-item__content o-neuron-post__content\">\n            <h5 class=\"o-portfolio-item__title o-neuron-post__title\"><a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/kmska-koninklijk-museum-voor-schone-kunsten-antwerp\">KMSKA Koninklijk Museum voor Schone Kunsten, Antwerp<\/a><\/h5>\n        <\/div>                <\/div>\n            <\/div>\n                                <div class=\"selector col-lg-6 architecture city photography travel post-31196 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-architecture portfolio_category-city portfolio_category-photography portfolio_category-travel\" data-id=\"31196\" data-columns=\"2-columns\">\n                <div class=\"o-post o-portfolio-item wow h-fadeInNeuron\" >\n                        <div class=\"o-neuron-hover\">\n        <div class=\"o-neuron-hover-holder\">\n            <div class=\"o-neuron-hover-holder__header\">\n                                    <a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/new-york\" class=\"o-neuron-hover-holder__header__media\">\n                                                    <div class=\"h-calculated-image\" style=\"padding-bottom: 100.000000% !important;\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/a2208c_bdf1063591374222a29a07e76a7da4e8_mv2_d_2526_1420_s_2-300x300.jpg\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/a2208c_bdf1063591374222a29a07e76a7da4e8_mv2_d_2526_1420_s_2-300x300.jpg 300w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/a2208c_bdf1063591374222a29a07e76a7da4e8_mv2_d_2526_1420_s_2-150x150.jpg 150w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/a2208c_bdf1063591374222a29a07e76a7da4e8_mv2_d_2526_1420_s_2-500x500.jpg 500w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/a2208c_bdf1063591374222a29a07e76a7da4e8_mv2_d_2526_1420_s_2-1000x1000.jpg 1000w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/a2208c_bdf1063591374222a29a07e76a7da4e8_mv2_d_2526_1420_s_2-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>                            <\/div>\n                                            <\/a>\n                                            <\/div>\n                    <\/div>\n    <\/div>\n<div class=\"o-portfolio-item__content o-neuron-post__content\">\n            <h5 class=\"o-portfolio-item__title o-neuron-post__title\"><a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/new-york\">New York<\/a><\/h5>\n        <\/div>                <\/div>\n            <\/div>\n                                <div class=\"selector col-lg-6 city photography travel post-31273 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-city portfolio_category-photography portfolio_category-travel\" data-id=\"31273\" data-columns=\"2-columns\">\n                <div class=\"o-post o-portfolio-item wow h-fadeInNeuron\" >\n                        <div class=\"o-neuron-hover\">\n        <div class=\"o-neuron-hover-holder\">\n            <div class=\"o-neuron-hover-holder__header\">\n                                    <a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/redentore\" class=\"o-neuron-hover-holder__header__media\">\n                                                    <div class=\"h-calculated-image\" style=\"padding-bottom: 100.000000% !important;\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/a2208c_f2177432b42746eaa9510352a3e2036f_mv2_d_2048_1536_s_2-300x300.jpg\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/a2208c_f2177432b42746eaa9510352a3e2036f_mv2_d_2048_1536_s_2-300x300.jpg 300w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/a2208c_f2177432b42746eaa9510352a3e2036f_mv2_d_2048_1536_s_2-150x150.jpg 150w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/a2208c_f2177432b42746eaa9510352a3e2036f_mv2_d_2048_1536_s_2-500x500.jpg 500w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/a2208c_f2177432b42746eaa9510352a3e2036f_mv2_d_2048_1536_s_2-1000x1000.jpg 1000w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/a2208c_f2177432b42746eaa9510352a3e2036f_mv2_d_2048_1536_s_2-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>                            <\/div>\n                                            <\/a>\n                                            <\/div>\n                    <\/div>\n    <\/div>\n<div class=\"o-portfolio-item__content o-neuron-post__content\">\n            <h5 class=\"o-portfolio-item__title o-neuron-post__title\"><a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/redentore\">Redentore<\/a><\/h5>\n        <\/div>                <\/div>\n            <\/div>\n                                <div class=\"selector col-lg-6 architecture photography post-40590 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-architecture portfolio_category-photography\" data-id=\"40590\" data-columns=\"2-columns\">\n                <div class=\"o-post o-portfolio-item wow h-fadeInNeuron\" >\n                        <div class=\"o-neuron-hover\">\n        <div class=\"o-neuron-hover-holder\">\n            <div class=\"o-neuron-hover-holder__header\">\n                                    <a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/richard-gilder-center-for-science-education-and-innovation-new-york-city\" class=\"o-neuron-hover-holder__header__media\">\n                                                    <div class=\"h-calculated-image\" style=\"padding-bottom: 66.650391% !important;\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2023\/10\/L1390258.jpg\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2023\/10\/L1390258.jpg 2048w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2023\/10\/L1390258-300x200.jpg 300w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2023\/10\/L1390258-1024x683.jpg 1024w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2023\/10\/L1390258-768x512.jpg 768w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2023\/10\/L1390258-1536x1024.jpg 1536w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2023\/10\/L1390258-18x12.jpg 18w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/>                            <\/div>\n                                            <\/a>\n                                            <\/div>\n                    <\/div>\n    <\/div>\n<div class=\"o-portfolio-item__content o-neuron-post__content\">\n            <h5 class=\"o-portfolio-item__title o-neuron-post__title\"><a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/richard-gilder-center-for-science-education-and-innovation-new-york-city\">Richard Gilder Center, New York City<\/a><\/h5>\n        <\/div>                <\/div>\n            <\/div>\n                                <div class=\"selector col-lg-6 architecture photography post-39435 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-architecture portfolio_category-photography\" data-id=\"39435\" data-columns=\"2-columns\">\n                <div class=\"o-post o-portfolio-item wow h-fadeInNeuron\" >\n                        <div class=\"o-neuron-hover\">\n        <div class=\"o-neuron-hover-holder\">\n            <div class=\"o-neuron-hover-holder__header\">\n                                    <a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/palazzo-dei-diamanti-ferrara\" class=\"o-neuron-hover-holder__header__media\">\n                                                    <div class=\"h-calculated-image\" style=\"padding-bottom: 66.679688% !important;\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2023\/03\/MP_Diamanti_FE-12-scaled.jpg\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2023\/03\/MP_Diamanti_FE-12-scaled.jpg 2560w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2023\/03\/MP_Diamanti_FE-12-300x200.jpg 300w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2023\/03\/MP_Diamanti_FE-12-1024x683.jpg 1024w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2023\/03\/MP_Diamanti_FE-12-768x512.jpg 768w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2023\/03\/MP_Diamanti_FE-12-1536x1024.jpg 1536w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2023\/03\/MP_Diamanti_FE-12-2048x1365.jpg 2048w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2023\/03\/MP_Diamanti_FE-12-18x12.jpg 18w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>                            <\/div>\n                                            <\/a>\n                                            <\/div>\n                    <\/div>\n    <\/div>\n<div class=\"o-portfolio-item__content o-neuron-post__content\">\n            <h5 class=\"o-portfolio-item__title o-neuron-post__title\"><a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/palazzo-dei-diamanti-ferrara\">Palazzo dei Diamanti, Ferrara<\/a><\/h5>\n        <\/div>                <\/div>\n            <\/div>\n                                <div class=\"selector col-lg-6 architecture photography post-38387 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-architecture portfolio_category-photography\" data-id=\"38387\" data-columns=\"2-columns\">\n                <div class=\"o-post o-portfolio-item wow h-fadeInNeuron\" >\n                        <div class=\"o-neuron-hover\">\n        <div class=\"o-neuron-hover-holder\">\n            <div class=\"o-neuron-hover-holder__header\">\n                                    <a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/de-ark-housing-dessel-studio-farris\" class=\"o-neuron-hover-holder__header__media\">\n                                                    <div class=\"h-calculated-image\" style=\"padding-bottom: 66.700000% !important;\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"1334\" src=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2022\/08\/SGF_DE_ARK_16_M_20210917-L1210077.jpeg\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2022\/08\/SGF_DE_ARK_16_M_20210917-L1210077.jpeg 2000w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2022\/08\/SGF_DE_ARK_16_M_20210917-L1210077-300x200.jpeg 300w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2022\/08\/SGF_DE_ARK_16_M_20210917-L1210077-1024x683.jpeg 1024w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2022\/08\/SGF_DE_ARK_16_M_20210917-L1210077-768x512.jpeg 768w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2022\/08\/SGF_DE_ARK_16_M_20210917-L1210077-1536x1025.jpeg 1536w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2022\/08\/SGF_DE_ARK_16_M_20210917-L1210077-18x12.jpeg 18w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/>                            <\/div>\n                                            <\/a>\n                                            <\/div>\n                    <\/div>\n    <\/div>\n<div class=\"o-portfolio-item__content o-neuron-post__content\">\n            <h5 class=\"o-portfolio-item__title o-neuron-post__title\"><a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/de-ark-housing-dessel-studio-farris\">De Ark Housing, Dessel, Studio Farris<\/a><\/h5>\n        <\/div>                <\/div>\n            <\/div>\n                                <div class=\"selector col-lg-6 architecture photography travel post-30643 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-architecture portfolio_category-photography portfolio_category-travel\" data-id=\"30643\" data-columns=\"2-columns\">\n                <div class=\"o-post o-portfolio-item wow h-fadeInNeuron\" >\n                        <div class=\"o-neuron-hover\">\n        <div class=\"o-neuron-hover-holder\">\n            <div class=\"o-neuron-hover-holder__header\">\n                                    <a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/side-portfolio-v5-2\" class=\"o-neuron-hover-holder__header__media\">\n                                                    <div class=\"h-calculated-image\" style=\"padding-bottom: 100.000000% !important;\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/a2208c_a52ed5dbbd6748e2948e9afe56ed743e-mv2_d_2049_2049_s_2-300x300.jpg\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/a2208c_a52ed5dbbd6748e2948e9afe56ed743e-mv2_d_2049_2049_s_2-300x300.jpg 300w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/a2208c_a52ed5dbbd6748e2948e9afe56ed743e-mv2_d_2049_2049_s_2-150x150.jpg 150w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/a2208c_a52ed5dbbd6748e2948e9afe56ed743e-mv2_d_2049_2049_s_2-768x768.jpg 768w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/a2208c_a52ed5dbbd6748e2948e9afe56ed743e-mv2_d_2049_2049_s_2-1024x1024.jpg 1024w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/a2208c_a52ed5dbbd6748e2948e9afe56ed743e-mv2_d_2049_2049_s_2-500x500.jpg 500w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/a2208c_a52ed5dbbd6748e2948e9afe56ed743e-mv2_d_2049_2049_s_2-1000x1000.jpg 1000w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/a2208c_a52ed5dbbd6748e2948e9afe56ed743e-mv2_d_2049_2049_s_2-600x600.jpg 600w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/10\/a2208c_a52ed5dbbd6748e2948e9afe56ed743e-mv2_d_2049_2049_s_2-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>                            <\/div>\n                                            <\/a>\n                                            <\/div>\n                    <\/div>\n    <\/div>\n<div class=\"o-portfolio-item__content o-neuron-post__content\">\n            <h5 class=\"o-portfolio-item__title o-neuron-post__title\"><a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/side-portfolio-v5-2\">Fondazione Prada Milano<\/a><\/h5>\n        <\/div>                <\/div>\n            <\/div>\n                                <div class=\"selector col-lg-6 photography travel post-32714 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-photography portfolio_category-travel\" data-id=\"32714\" data-columns=\"2-columns\">\n                <div class=\"o-post o-portfolio-item wow h-fadeInNeuron\" >\n                        <div class=\"o-neuron-hover\">\n        <div class=\"o-neuron-hover-holder\">\n            <div class=\"o-neuron-hover-holder__header\">\n                                    <a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/puglia\" class=\"o-neuron-hover-holder__header__media\">\n                                                    <div class=\"h-calculated-image\" style=\"padding-bottom: 66.718750% !important;\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"854\" src=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/12\/1_cmhFIi8Shxb2cqBVHSVllw.jpg\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/12\/1_cmhFIi8Shxb2cqBVHSVllw.jpg 1280w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/12\/1_cmhFIi8Shxb2cqBVHSVllw-300x200.jpg 300w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/12\/1_cmhFIi8Shxb2cqBVHSVllw-1024x683.jpg 1024w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/12\/1_cmhFIi8Shxb2cqBVHSVllw-768x512.jpg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>                            <\/div>\n                                            <\/a>\n                                            <\/div>\n                    <\/div>\n    <\/div>\n<div class=\"o-portfolio-item__content o-neuron-post__content\">\n            <h5 class=\"o-portfolio-item__title o-neuron-post__title\"><a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/puglia\">Puglia<\/a><\/h5>\n        <\/div>                <\/div>\n            <\/div>\n                                <div class=\"selector col-lg-6 architecture city photography travel post-32641 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-architecture portfolio_category-city portfolio_category-photography portfolio_category-travel\" data-id=\"32641\" data-columns=\"2-columns\">\n                <div class=\"o-post o-portfolio-item wow h-fadeInNeuron\" >\n                        <div class=\"o-neuron-hover\">\n        <div class=\"o-neuron-hover-holder\">\n            <div class=\"o-neuron-hover-holder__header\">\n                                    <a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/berlin\" class=\"o-neuron-hover-holder__header__media\">\n                                                    <div class=\"h-calculated-image\" style=\"padding-bottom: 75.000000% !important;\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1536\" src=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/11\/a2208c_4d6271e6f64446d7ac870c3aafb25be3_mv2_d_2048_1536_s_2.jpg\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/11\/a2208c_4d6271e6f64446d7ac870c3aafb25be3_mv2_d_2048_1536_s_2.jpg 2048w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/11\/a2208c_4d6271e6f64446d7ac870c3aafb25be3_mv2_d_2048_1536_s_2-300x225.jpg 300w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/11\/a2208c_4d6271e6f64446d7ac870c3aafb25be3_mv2_d_2048_1536_s_2-1024x768.jpg 1024w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/11\/a2208c_4d6271e6f64446d7ac870c3aafb25be3_mv2_d_2048_1536_s_2-768x576.jpg 768w, https:\/\/martinopietropoli.com\/wp-content\/uploads\/2019\/11\/a2208c_4d6271e6f64446d7ac870c3aafb25be3_mv2_d_2048_1536_s_2-1536x1152.jpg 1536w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/>                            <\/div>\n                                            <\/a>\n                                            <\/div>\n                    <\/div>\n    <\/div>\n<div class=\"o-portfolio-item__content o-neuron-post__content\">\n            <h5 class=\"o-portfolio-item__title o-neuron-post__title\"><a href=\"https:\/\/martinopietropoli.com\/en\/portfolio\/berlin\">Berlin<\/a><\/h5>\n        <\/div>                <\/div>\n            <\/div>\n            <\/div>\n\n\n<div class='o-pagination'><div class='container'><div class='row align-items-center h-medium-top-padding h-medium-bottom-padding'><div class='o-pagination__arrow d-inline-flex col-2 o-pagination__arrow--disabled'><a class=\"bifrost-link d-inline-flex\" href='https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/pages\/29866'><svg xmlns='http:\/\/www.w3.org\/2000\/svg' width='22' height='22' viewbox='0 0 24 24' fill='none' stroke-width='2' stroke-linecap='round' stroke-linejoin='round' class='feather feather-chevron-left'><polyline points='15 18 9 12 15 6'><\/polyline><\/svg><\/a><\/div><ul class='col-8 h-align-center o-pagination__numbers'><li class=\"active\"><a>1<\/a><\/li><li><a href='https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/pages\/29866\/page\/2' class=\"inactive bifrost-link\">2<\/a><\/li><\/ul><div class='o-pagination__arrow d-inline-flex col-2'><a class=\"bifrost-link d-inline-flex ml-auto\" href='https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/pages\/29866\/page\/2'><svg xmlns='http:\/\/www.w3.org\/2000\/svg' width='22' height='22' viewbox='0 0 24 24' fill='none' stroke-width='2' stroke-linecap='round' stroke-linejoin='round' class='feather feather-chevron-right'><polyline points='9 18 15 12 9 6'><\/polyline><\/svg><\/a><\/div><\/div><\/div><\/div>\n\n\n\t\t\t<\/div>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b68a604 elementor-section-boxed elementor-section-height-default elementor-section-height-default neuron-fixed-no\" data-id=\"b68a604\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c87c2fc\" data-id=\"c87c2fc\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1fb628c elementor-widget elementor-widget-spacer\" data-id=\"1fb628c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d71a086 elementor-widget elementor-widget-spacer\" data-id=\"d71a086\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Fotografia Fotografo da decenni. Architettura, reportage, luoghi, spesso e soprattutto quelli che non si degna mai di uno&#8230;<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-29866","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/pages\/29866","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/comments?post=29866"}],"version-history":[{"count":0,"href":"https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/pages\/29866\/revisions"}],"wp:attachment":[{"href":"https:\/\/martinopietropoli.com\/en\/wp-json\/wp\/v2\/media?parent=29866"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}